{"id":1674,"date":"2021-01-14T07:30:28","date_gmt":"2021-01-14T07:30:28","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=1674"},"modified":"2021-01-14T07:30:28","modified_gmt":"2021-01-14T07:30:28","slug":"concejos-enero","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/","title":{"rendered":"Mapa Covid por Concejos &#8211;  Enero &#8211;"},"content":{"rendered":"<p style=\"text-align: justify;\">La<strong> incidencia por concejos del coronavirus <\/strong>deja un mapa de riesgo muy desigual en el Principado. Seg\u00fan los datos que facilita el<strong> Observatorio de Salud de Asturias <\/strong>y teniendo en cuenta el &#8216;sem\u00e1foro&#8217; del Ministerio de Sanidad, ya hay nueve municipios en riesgo muy alto en cuanto a la incidencia acumulada a 7 d\u00edas. <strong>Cangas del Narcea, Villay\u00f3n, Tapia de Casariego, Belmonte de Miranda, Grado, Candamo, Illas, Castrill\u00f3n, y Santo Adriano<\/strong> se encuentran en nivel 4 de alerta. A estos le siguen, un nivel por debajo, Oviedo, Avil\u00e9s, Tineo, San Mart\u00edn del Rey Aurelio, Nore\u00f1a, Ribadedeva, Llanes, Colunga, Goz\u00f3n, Corvera y Soto del Barco. En el nivel de riesgo 2 (medio) est\u00e1n quince municipios asturianos, entre ellos, <strong>Gij\u00f3n<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Por contra, <strong>Laviana y Carre\u00f1o <\/strong>est\u00e1n en riesgo bajo y m\u00e1s de la mitad de los concejos, 41 en total, se encuentran fuera de peligro, en la denominada \u00abnueva normalidad\u00bb.<\/p>\n<div id=\"_wmass_114\" style=\"text-align: justify;\">\n<div id=\"jw-s_114114\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1675 size-full\" src=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/mapa-covid-12.jpg\" alt=\"\" width=\"1524\" height=\"557\" srcset=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/mapa-covid-12.jpg 1524w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/mapa-covid-12-300x110.jpg 300w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/mapa-covid-12-1024x374.jpg 1024w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/mapa-covid-12-768x281.jpg 768w\" sizes=\"auto, (max-width: 1524px) 100vw, 1524px\" \/><\/div>\n<\/div>\n<p style=\"text-align: justify;\">La incidencia acumulada a 7 d\u00edas es uno de los ocho factores establecidos por el <strong>Ministerio de Sanidad <\/strong>para conocer en qu\u00e9 nivel de riesgo frente a la covid se encuentra cada comunidad aut\u00f3noma. El resto de los indicadores son la incidencia a 7 d\u00edas de mayores de 65 a\u00f1os (considerados grupo de riesgo), la incidencia a dos semanas en la poblaci\u00f3n general, la positividad, la trazabilidad, la ocupaci\u00f3n de camas de hospitalizaci\u00f3n y las de cuidados intensivos.<\/p>\n<p style=\"text-align: justify;\">En cuanto a la incidencia acumulada a 7 d\u00edas en mayores de 65 a\u00f1os, son catorce los concejos en riesgo muy alto.<strong> Llanes, Colunga, Avil\u00e9s, Corvera, Illas, Candamo, Grado, San Mart\u00edn del Rey Aurelio, Langreo, Nore\u00f1a, Mieres, Morc\u00edn, Cangas del Narcea y Tapia de Casariego<\/strong> son los municipios cuyos datos por cada 100.000 habitantes est\u00e1n en la alerta 4. En cuanto al porcentaje de casos diagnosticados en la \u00faltima semana (tasa de positividad) son seis en riesgo muy alto: Santa Eulalia de Oscos, Sariego, Nore\u00f1a, Illas, Grado y Cangas del Narcea.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan todos los indicadores del Ministerio de Sanidad, la regi\u00f3n se sit\u00faa en el nivel m\u00e1ximo de transmisi\u00f3n, con una incidencia a 7 d\u00edas de 141,67 por cada 100.000 habitantes y esta misma en mayores de 65 a\u00f1os, en los 129,28 casos por cada 100.000. Mientras, la positividad se mantiene en el nivel 2, esto es, medio, con un 7,14%. La tasa de trazabilidad tambi\u00e9n se sit\u00faa en el nivel medio de alerta con un 61,1%. En el nivel asistencial, la regi\u00f3n est\u00e1 en alerta 3, alta, con una ocupaci\u00f3n de camas de hospitalizaci\u00f3n del 8,47% (nivel 2) y de cuidados intensivos de 16,77% (nivel 3, alto).<\/p>\n<p style=\"text-align: justify;\">La situaci\u00f3n actual en cuanto a la incidencia acumulada a 7 d\u00edas se sit\u00faa en cifras similares a las del 5 de diciembre. La diferencia entre ambos momentos es que por aquel entonces la curva era descendiente, coincidiendo con el final de la segunda ola, y ahora est\u00e1 aumentando diariamente, debido a la entrada en la tercera, tanto a nivel auton\u00f3mico como nacional.<\/p>\n<p><a href=\"https:\/\/obsaludasturias.com\/obsa\/\">Observatorio de Salud<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La incidencia por concejos del coronavirus deja un mapa de riesgo muy desigual en el Principado. Seg\u00fan los datos que facilita el Observatorio de Salud de Asturias y teniendo en cuenta el &#8216;sem\u00e1foro&#8217; del Ministerio de Sanidad, ya hay nueve municipios en riesgo muy alto en cuanto a la incidencia acumulada a 7 d\u00edas. Cangas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,6,49,8],"tags":[92],"class_list":["post-1674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caudal","category-noticias","category-covid","category-nalon","tag-covid19"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mapa Covid por Concejos - Enero - CuencasMineras.com<\/title>\n<meta name=\"description\" content=\"La incidencia por concejos del coronavirus deja un mapa de riesgo muy desigual en el Principado. Seg\u00fan los datos que facilita el Observatorio de Salud de Asturias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mapa Covid por Concejos - Enero - CuencasMineras.com\" \/>\n<meta property=\"og:description\" content=\"La incidencia por concejos del coronavirus deja un mapa de riesgo muy desigual en el Principado. Seg\u00fan los datos que facilita el Observatorio de Salud de Asturias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-14T07:30:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/mapa-covid-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1524\" \/>\n\t<meta property=\"og:image:height\" content=\"557\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/14\\\/concejos-enero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/14\\\/concejos-enero\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"Mapa Covid por Concejos &#8211; Enero &#8211;\",\"datePublished\":\"2021-01-14T07:30:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/14\\\/concejos-enero\\\/\"},\"wordCount\":515,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/14\\\/concejos-enero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/mapa-covid-12.jpg\",\"keywords\":[\"Covid19\"],\"articleSection\":[\"Caudal\",\"CM NEWS\",\"COVID-19\",\"Nal\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/14\\\/concejos-enero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/14\\\/concejos-enero\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/14\\\/concejos-enero\\\/\",\"name\":\"Mapa Covid por Concejos - Enero - CuencasMineras.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/14\\\/concejos-enero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/14\\\/concejos-enero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/mapa-covid-12.jpg\",\"datePublished\":\"2021-01-14T07:30:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"description\":\"La incidencia por concejos del coronavirus deja un mapa de riesgo muy desigual en el Principado. Seg\u00fan los datos que facilita el Observatorio de Salud de Asturias\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/14\\\/concejos-enero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/14\\\/concejos-enero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/14\\\/concejos-enero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/mapa-covid-12.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/mapa-covid-12.jpg\",\"width\":1524,\"height\":557},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/14\\\/concejos-enero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapa Covid por Concejos &#8211; Enero &#8211;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mapa Covid por Concejos - Enero - CuencasMineras.com","description":"La incidencia por concejos del coronavirus deja un mapa de riesgo muy desigual en el Principado. Seg\u00fan los datos que facilita el Observatorio de Salud de Asturias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/","og_locale":"es_ES","og_type":"article","og_title":"Mapa Covid por Concejos - Enero - CuencasMineras.com","og_description":"La incidencia por concejos del coronavirus deja un mapa de riesgo muy desigual en el Principado. Seg\u00fan los datos que facilita el Observatorio de Salud de Asturias","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/","article_published_time":"2021-01-14T07:30:28+00:00","og_image":[{"width":1524,"height":557,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/mapa-covid-12.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"Mapa Covid por Concejos &#8211; Enero &#8211;","datePublished":"2021-01-14T07:30:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/"},"wordCount":515,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/mapa-covid-12.jpg","keywords":["Covid19"],"articleSection":["Caudal","CM NEWS","COVID-19","Nal\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/","name":"Mapa Covid por Concejos - Enero - CuencasMineras.com","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/mapa-covid-12.jpg","datePublished":"2021-01-14T07:30:28+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"description":"La incidencia por concejos del coronavirus deja un mapa de riesgo muy desigual en el Principado. Seg\u00fan los datos que facilita el Observatorio de Salud de Asturias","breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/mapa-covid-12.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/mapa-covid-12.jpg","width":1524,"height":557},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/14\/concejos-enero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"Mapa Covid por Concejos &#8211; Enero &#8211;"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/1674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=1674"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/1674\/revisions"}],"predecessor-version":[{"id":1676,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/1674\/revisions\/1676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/1675"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=1674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=1674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=1674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}