{"id":1687,"date":"2021-01-16T15:15:26","date_gmt":"2021-01-16T15:15:26","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=1687"},"modified":"2021-01-16T15:15:26","modified_gmt":"2021-01-16T15:15:26","slug":"un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/","title":{"rendered":"Un herido tras el vuelco de un tractor en una plantaci\u00f3n de fruta en Langreo"},"content":{"rendered":"<p class=\"article-body__text article-body__text--entry article-body__text-middle\">Un hombre result\u00f3 herido ayer al caer por un desnivel y volcar el tractor con el que trabajaba en una plantaci\u00f3n de fruta en la localidad de Caufel, en el distrito langreano de Lada. El var\u00f3n lesionado, que qued\u00f3 atrapado por una pierna en el veh\u00edculo, fue evacuado en la UVI m\u00f3vil de la zona al hospital Valle del Nal\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1688\" src=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3-300x225.jpg\" alt=\"\" width=\"440\" height=\"330\" srcset=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3-300x225.jpg 300w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3-768x576.jpg 768w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3.jpg 1024w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/p>\n<p class=\"article-body__text \">El Centro de Coordinaci\u00f3n de Emergencias recibi\u00f3 pasadas las dos y veinte de la tarde un aviso en el que se indicaba que un tractor se hab\u00eda precipitado por una pendiente en Langreo. Se moviliz\u00f3 a seis bomberos con base en el parque de San Mart\u00edn del Rey Aurelio, que se trasladaron al lugar del accidente con un veh\u00edculo ligero, el furg\u00f3n multisocorro y el veh\u00edculo \u201cprimera salida\u201d.<\/p>\n<p class=\"article-body__text \">Al llegar a la zona indicada, el operativo comprob\u00f3 que el veh\u00edculo estaba volcado sobre un lateral y su ocupante, atrapado por una pierna. Los bomberos utilizaron los cojines neum\u00e1ticos para levantar con seguridad el tractor y poder as\u00ed extraer al conductor. Con ayuda de la \u201ccamilla nido\u201d, portearon al var\u00f3n accidentado hasta la ambulancia.<\/p>\n<p class=\"article-body__text \">La dotaci\u00f3n de bomberos dio por finalizada la intervenci\u00f3n a su retorno a la base, que qued\u00f3 registrada a las 15:56 horas. La sala del 112 del Servicio de Emergencias del Principado (SEPA) dio cuenta del accidente y de la actuaci\u00f3n a la Guardia Civil, al Servicio de Atenci\u00f3n M\u00e9dica Urgente (SAMU) y a la autoridad laboral. El incidente viene a prolongar un inicio de a\u00f1o que ha sido particularmente conflictivo en lo tocante a la siniestralidad laboral en Asturias. En la parte m\u00e1s tr\u00e1gica de esta primera mitad de enero figuran los dos accidentes con v\u00edctimas mortales, el del operario de una quitanieves sepultado por un alud en San Isidro (donde todav\u00eda se busca a su compa\u00f1ero desaparecido) y el del t\u00e9cnico de emergencias sanitarias que perdi\u00f3 la vida en la madrugada del pasado s\u00e1bado en Gij\u00f3n.<\/p>\n<p>Fuente: LNE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un hombre result\u00f3 herido ayer al caer por un desnivel y volcar el tractor con el que trabajaba en una plantaci\u00f3n de fruta en la localidad de Caufel, en el distrito langreano de Lada. El var\u00f3n lesionado, que qued\u00f3 atrapado por una pierna en el veh\u00edculo, fue evacuado en la UVI m\u00f3vil de la zona [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,8],"tags":[],"class_list":["post-1687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-nalon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un herido tras el vuelco de un tractor en una plantaci\u00f3n de fruta en Langreo -<\/title>\n<meta name=\"description\" content=\"El veh\u00edculo se precipit\u00f3 por un desnivel en la localidad de Caufel, parroquia de Lada, y su ocupante qued\u00f3 atrapado por una pierna\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un herido tras el vuelco de un tractor en una plantaci\u00f3n de fruta en Langreo -\" \/>\n<meta property=\"og:description\" content=\"El veh\u00edculo se precipit\u00f3 por un desnivel en la localidad de Caufel, parroquia de Lada, y su ocupante qued\u00f3 atrapado por una pierna\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-16T15:15:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/16\\\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/16\\\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"Un herido tras el vuelco de un tractor en una plantaci\u00f3n de fruta en Langreo\",\"datePublished\":\"2021-01-16T15:15:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/16\\\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\\\/\"},\"wordCount\":365,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/16\\\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3.jpg\",\"articleSection\":[\"CM NEWS\",\"Nal\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/16\\\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/16\\\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/16\\\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\\\/\",\"name\":\"Un herido tras el vuelco de un tractor en una plantaci\u00f3n de fruta en Langreo -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/16\\\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/16\\\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3.jpg\",\"datePublished\":\"2021-01-16T15:15:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"description\":\"El veh\u00edculo se precipit\u00f3 por un desnivel en la localidad de Caufel, parroquia de Lada, y su ocupante qued\u00f3 atrapado por una pierna\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/16\\\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/16\\\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/16\\\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/01\\\/16\\\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un herido tras el vuelco de un tractor en una plantaci\u00f3n de fruta en Langreo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un herido tras el vuelco de un tractor en una plantaci\u00f3n de fruta en Langreo -","description":"El veh\u00edculo se precipit\u00f3 por un desnivel en la localidad de Caufel, parroquia de Lada, y su ocupante qued\u00f3 atrapado por una pierna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/","og_locale":"es_ES","og_type":"article","og_title":"Un herido tras el vuelco de un tractor en una plantaci\u00f3n de fruta en Langreo -","og_description":"El veh\u00edculo se precipit\u00f3 por un desnivel en la localidad de Caufel, parroquia de Lada, y su ocupante qued\u00f3 atrapado por una pierna","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/","article_published_time":"2021-01-16T15:15:26+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"Un herido tras el vuelco de un tractor en una plantaci\u00f3n de fruta en Langreo","datePublished":"2021-01-16T15:15:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/"},"wordCount":365,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3.jpg","articleSection":["CM NEWS","Nal\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/","name":"Un herido tras el vuelco de un tractor en una plantaci\u00f3n de fruta en Langreo -","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3.jpg","datePublished":"2021-01-16T15:15:26+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"description":"El veh\u00edculo se precipit\u00f3 por un desnivel en la localidad de Caufel, parroquia de Lada, y su ocupante qued\u00f3 atrapado por una pierna","breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/01\/vivienda-colectiva-edificio-vpp-lada-langreo-roces-arquitectos-asturias-3.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/01\/16\/un-herido-tras-el-vuelco-de-un-tractor-en-una-plantacion-de-fruta-en-langreo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"Un herido tras el vuelco de un tractor en una plantaci\u00f3n de fruta en Langreo"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/1687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=1687"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/1687\/revisions"}],"predecessor-version":[{"id":1689,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/1687\/revisions\/1689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/1688"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=1687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=1687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=1687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}