{"id":2332,"date":"2021-04-04T12:28:08","date_gmt":"2021-04-04T12:28:08","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=2332"},"modified":"2021-04-04T12:28:08","modified_gmt":"2021-04-04T12:28:08","slug":"el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/","title":{"rendered":"El hospital de animales de Redes afronta los remates finales de obra para abrir este verano"},"content":{"rendered":"<p style=\"text-align: justify;\">l Principado acomete los \u00faltimos remates de obra en el hospital de la fauna de Redes. Las labores se han centrado en los \u00faltimos d\u00edas en la instalaci\u00f3n de un cierre perimetral alrededor del complejo. Tambi\u00e9n se han acondicionado los accesos con tareas de desbroce y se han colocado contenedores de basura. La previsi\u00f3n del Gobierno regional es que pueda empezar a funcionar en verano, seg\u00fan indic\u00f3 el consejero de Medio Rural y Cohesi\u00f3n Territorial, Alejandro Calvo, en una visita realizada a Campo de caso hace dos semanas.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-2333\" src=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/04\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0-1024x438.jpg\" alt=\"\" width=\"640\" height=\"274\" srcset=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/04\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0-1024x438.jpg 1024w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/04\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0-300x128.jpg 300w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/04\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0-768x329.jpg 768w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/04\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0.jpg 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">\nLas instalaciones, construidas con 4,5 millones de euros y que suman diez a\u00f1os de inactividad, est\u00e1n ubicadas en El Castr\u00edn (en Sobrescobio) y ofrecer\u00e1n la posibilidad de realizar visitas para conocer el trabajo que se desarrollar\u00e1 en su interior. El centro de recuperaci\u00f3n de animales dispondr\u00e1, en concreto, de un aula de interpretaci\u00f3n en el que se recibir\u00e1 a los visitantes. El Principado incluy\u00f3 en el Presupuesto del pasado a\u00f1o una partida de 125.000 euros para abordar los trabajos en las acometidas de agua y electricidad.<\/p>\n<p style=\"text-align: justify;\">Las dependencias carec\u00edan de tra\u00edda de agua y ten\u00edan reparaciones el\u00e9ctricas pendientes tras el robo de gran parte del cobre de los tendidos y cuadros de las instalaciones. La inversi\u00f3n en el hospital de animales de Redes ascendi\u00f3 a 4,5 millones de euros y se planific\u00f3 para recuperar especies amenazadas y hacer m\u00e1s f\u00e1cil la vuelta a su h\u00e1bitat de animales heridos recogidos en el entorno natural. En estos a\u00f1os solo se ha utilizado en dos ocasiones, para tratar a las osas \u201cMolinera\u201d y \u201cLara\u201d, una intervenci\u00f3n que dur\u00f3 cuatro meses en total. El Principado hab\u00eda marcado plazos para su apertura en varias ocasiones pero se han ido acumulando los retrasos.<\/p>\n<p style=\"text-align: justify;\">En el complejo, que prestar\u00e1 servicio a toda Asturias, trabajar\u00e1 el personal del centro de recuperaci\u00f3n de la fauna que actualmente tiene su sede en Infiesto. Las obras de construcci\u00f3n del hospital de animales de Sobrescobio, que cuenta con 4.076 metros cuadrados de superficie, comenzaron en 2008. Este es uno de los proyectos que estaban incluidos en el Parque de la Fauna de Redes. En el dise\u00f1o original estaba prevista una segunda fase que no se ha llevado a cabo. El dise\u00f1o contemplaba la construcci\u00f3n de un cercado de 6,3 hect\u00e1reas de superficie, con unos miradores desde los que los visitantes podr\u00edan ver a los animales en proceso de recuperaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">El Parque de la Fauna deb\u00eda completarse con el centro de cr\u00eda en cautividad del urogallo, que lleva funcionando m\u00e1s de una d\u00e9cada, y con el aula de interpretaci\u00f3n de esta ave, que nunca se puso en marcha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>l Principado acomete los \u00faltimos remates de obra en el hospital de la fauna de Redes. Las labores se han centrado en los \u00faltimos d\u00edas en la instalaci\u00f3n de un cierre perimetral alrededor del complejo. Tambi\u00e9n se han acondicionado los accesos con tareas de desbroce y se han colocado contenedores de basura. La previsi\u00f3n del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2333,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,8],"tags":[],"class_list":["post-2332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-nalon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El hospital de animales de Redes afronta los remates finales de obra para abrir este verano - cm news<\/title>\n<meta name=\"description\" content=\"Las labores se est\u00e1n centrando en las \u00faltimas semanas en la instalaci\u00f3n de un cierre perimetral y en el acondicionamiento de los accesos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El hospital de animales de Redes afronta los remates finales de obra para abrir este verano - cm news\" \/>\n<meta property=\"og:description\" content=\"Las labores se est\u00e1n centrando en las \u00faltimas semanas en la instalaci\u00f3n de un cierre perimetral y en el acondicionamiento de los accesos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-04T12:28:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/04\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"548\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/04\\\/04\\\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/04\\\/04\\\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"El hospital de animales de Redes afronta los remates finales de obra para abrir este verano\",\"datePublished\":\"2021-04-04T12:28:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/04\\\/04\\\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\\\/\"},\"wordCount\":480,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/04\\\/04\\\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0.jpg\",\"articleSection\":[\"CM NEWS\",\"Nal\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/04\\\/04\\\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/04\\\/04\\\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/04\\\/04\\\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\\\/\",\"name\":\"El hospital de animales de Redes afronta los remates finales de obra para abrir este verano - cm news\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/04\\\/04\\\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/04\\\/04\\\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0.jpg\",\"datePublished\":\"2021-04-04T12:28:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"description\":\"Las labores se est\u00e1n centrando en las \u00faltimas semanas en la instalaci\u00f3n de un cierre perimetral y en el acondicionamiento de los accesos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/04\\\/04\\\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/04\\\/04\\\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/04\\\/04\\\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0.jpg\",\"width\":1280,\"height\":548},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/04\\\/04\\\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El hospital de animales de Redes afronta los remates finales de obra para abrir este verano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El hospital de animales de Redes afronta los remates finales de obra para abrir este verano - cm news","description":"Las labores se est\u00e1n centrando en las \u00faltimas semanas en la instalaci\u00f3n de un cierre perimetral y en el acondicionamiento de los accesos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/","og_locale":"es_ES","og_type":"article","og_title":"El hospital de animales de Redes afronta los remates finales de obra para abrir este verano - cm news","og_description":"Las labores se est\u00e1n centrando en las \u00faltimas semanas en la instalaci\u00f3n de un cierre perimetral y en el acondicionamiento de los accesos","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/","article_published_time":"2021-04-04T12:28:08+00:00","og_image":[{"width":1280,"height":548,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/04\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"El hospital de animales de Redes afronta los remates finales de obra para abrir este verano","datePublished":"2021-04-04T12:28:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/"},"wordCount":480,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/04\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0.jpg","articleSection":["CM NEWS","Nal\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/","name":"El hospital de animales de Redes afronta los remates finales de obra para abrir este verano - cm news","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/04\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0.jpg","datePublished":"2021-04-04T12:28:08+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"description":"Las labores se est\u00e1n centrando en las \u00faltimas semanas en la instalaci\u00f3n de un cierre perimetral y en el acondicionamiento de los accesos","breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/04\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/04\/c6597a50-0c31-4c67-852e-5616e61e08aa_21-9-aspect-ratio_default_0.jpg","width":1280,"height":548},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/04\/04\/el-hospital-de-animales-de-redes-afronta-los-remates-finales-de-obra-para-abrir-este-verano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"El hospital de animales de Redes afronta los remates finales de obra para abrir este verano"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=2332"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2332\/revisions"}],"predecessor-version":[{"id":2334,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2332\/revisions\/2334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/2333"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=2332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=2332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=2332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}