{"id":2614,"date":"2021-05-12T08:58:22","date_gmt":"2021-05-12T08:58:22","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=2614"},"modified":"2021-05-12T08:58:22","modified_gmt":"2021-05-12T08:58:22","slug":"los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/","title":{"rendered":"Los pueblos del norte de Mieres, unidos contra la quema de residuos en La Pereda"},"content":{"rendered":"<p style=\"text-align: justify;\">Las principales poblaciones de la zona norte de Mieres tienen previsto reunirse este viernes para articular un frente com\u00fan en rechazo a los planes de Hunosa de quemar residuos (Combustible S\u00f3lido Recuperado, CSR) en la t\u00e9rmica de La Pereda a partir del a\u00f1o que viene. \u201cNo lo vamos a permitir bajo ning\u00fan concepto. Es una l\u00ednea roja innegociable\u201d, explicaron ayer los portavoces de la sociedad civil.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-2615\" src=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513-1024x438.jpg\" alt=\"\" width=\"640\" height=\"274\" srcset=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513-1024x438.jpg 1024w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513-300x128.jpg 300w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513-768x329.jpg 768w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513.jpg 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">La Pereda, Loredo, La Rebollada, Cardeo, Barrio Pach\u00f3n, Valmuri\u00e1n, Pumardongo, El Cori\u00f3n y Abla\u00f1a ya han confirmado su presencia en la reuni\u00f3n del viernes. Las asociaciones tienen adem\u00e1s la pr\u00f3xima semana un encuentro con Hunosa. No tiene queja del trato de la empresa, pero son tajantes al rechazar la posibilidad de que en la central se puedan quemar residuos m\u00e1s o menos tratados previamente: \u201cAceptamos la biomasa y nada m\u00e1s\u201d, se\u00f1alan. La t\u00e9rmica de La Pereda, propiedad de Hunosa, se convertir\u00e1 en una planta de biomasa en un periodo de meses. En el segundo semestre de 2022 estar\u00e1 en disposici\u00f3n de quemar residuos madereros propios y ajenos, tras una r\u00e1pida transformaci\u00f3n desde la combusti\u00f3n carb\u00f3n y est\u00e9riles de mina a residuos ecol\u00f3gicamente m\u00e1s aceptables. El problema es que el proyecto recoge la posibilidad de quemas hasta un 25 por ciento de CSR, es decir, unas 85.000 toneladas al a\u00f1o. La iniciativa viene acompa\u00f1a de una previsi\u00f3n de generaci\u00f3n de empleo que se cifra alrededor de los 180 dentro del sector de la gesti\u00f3n forestal.<\/p>\n<p style=\"text-align: justify;\">Los vecinos subrayan que en ning\u00fan caso rechazan el plan de transformaci\u00f3n de la t\u00e9rmica. Lo que no aceptan es la quema de residuos. Las asociaciones ya est\u00e1n trabajando en la presentaci\u00f3n de alegaciones al proyecto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las principales poblaciones de la zona norte de Mieres tienen previsto reunirse este viernes para articular un frente com\u00fan en rechazo a los planes de Hunosa de quemar residuos (Combustible S\u00f3lido Recuperado, CSR) en la t\u00e9rmica de La Pereda a partir del a\u00f1o que viene. \u201cNo lo vamos a permitir bajo ning\u00fan concepto. Es una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,6],"tags":[],"class_list":["post-2614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caudal","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los pueblos del norte de Mieres, unidos contra la quema de residuos en La Pereda - cm news<\/title>\n<meta name=\"description\" content=\"Hasta nueve localidades ya se han sumado a un frente com\u00fan que busca limitar las combustiones en la t\u00e9rmica a biomasa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los pueblos del norte de Mieres, unidos contra la quema de residuos en La Pereda - cm news\" \/>\n<meta property=\"og:description\" content=\"Hasta nueve localidades ya se han sumado a un frente com\u00fan que busca limitar las combustiones en la t\u00e9rmica a biomasa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-12T08:58:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"548\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/12\\\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/12\\\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"Los pueblos del norte de Mieres, unidos contra la quema de residuos en La Pereda\",\"datePublished\":\"2021-05-12T08:58:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/12\\\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\\\/\"},\"wordCount\":322,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/12\\\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513.jpg\",\"articleSection\":[\"Caudal\",\"CM NEWS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/12\\\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/12\\\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/12\\\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\\\/\",\"name\":\"Los pueblos del norte de Mieres, unidos contra la quema de residuos en La Pereda - cm news\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/12\\\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/12\\\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513.jpg\",\"datePublished\":\"2021-05-12T08:58:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"description\":\"Hasta nueve localidades ya se han sumado a un frente com\u00fan que busca limitar las combustiones en la t\u00e9rmica a biomasa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/12\\\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/12\\\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/12\\\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513.jpg\",\"width\":1280,\"height\":548},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/12\\\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los pueblos del norte de Mieres, unidos contra la quema de residuos en La Pereda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los pueblos del norte de Mieres, unidos contra la quema de residuos en La Pereda - cm news","description":"Hasta nueve localidades ya se han sumado a un frente com\u00fan que busca limitar las combustiones en la t\u00e9rmica a biomasa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/","og_locale":"es_ES","og_type":"article","og_title":"Los pueblos del norte de Mieres, unidos contra la quema de residuos en La Pereda - cm news","og_description":"Hasta nueve localidades ya se han sumado a un frente com\u00fan que busca limitar las combustiones en la t\u00e9rmica a biomasa","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/","article_published_time":"2021-05-12T08:58:22+00:00","og_image":[{"width":1280,"height":548,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"Los pueblos del norte de Mieres, unidos contra la quema de residuos en La Pereda","datePublished":"2021-05-12T08:58:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/"},"wordCount":322,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513.jpg","articleSection":["Caudal","CM NEWS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/","name":"Los pueblos del norte de Mieres, unidos contra la quema de residuos en La Pereda - cm news","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513.jpg","datePublished":"2021-05-12T08:58:22+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"description":"Hasta nueve localidades ya se han sumado a un frente com\u00fan que busca limitar las combustiones en la t\u00e9rmica a biomasa","breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/af8a20bf-3f15-4518-97eb-b3084be381af_21-9-aspect-ratio_default_0_x409y513.jpg","width":1280,"height":548},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/12\/los-pueblos-del-norte-de-mieres-unidos-contra-la-quema-de-residuos-en-la-pereda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"Los pueblos del norte de Mieres, unidos contra la quema de residuos en La Pereda"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=2614"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2614\/revisions"}],"predecessor-version":[{"id":2616,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2614\/revisions\/2616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/2615"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=2614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=2614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=2614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}