{"id":2650,"date":"2021-05-14T12:02:58","date_gmt":"2021-05-14T12:02:58","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=2650"},"modified":"2021-05-14T12:02:58","modified_gmt":"2021-05-14T12:02:58","slug":"pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/","title":{"rendered":"PP MIERES solicita que se cree un PLAN DE CALIDAD DE AIRE"},"content":{"rendered":"<p align=\"JUSTIFY\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\">Ante las pol\u00e9micas surgidas en las \u00faltimas semanas en el Concejo:<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><b>El Grupo Municipal del Partido Popular solicita que se cree un PLAN DE CALIDAD DE AIRE para el Concejo de Mieres.<\/b><\/span><\/span><\/p>\n<ul>\n<li>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><b>Dicho Plan ha de contener mejoras de control de la calidad del aire as\u00ed como mejoras de la informaci\u00f3n, participaci\u00f3n y difusi\u00f3n ante la ciudadan\u00eda, mejoras en la movilidad, subvenciones, actuaciones ante cabio clim\u00e1tico, entre otros. <\/b><\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p align=\"JUSTIFY\">\n<p><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><u><b>13<\/b><\/u><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><u><b>, <\/b><\/u><\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><u><b>mayo<\/b><\/u><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><u><b> 202<\/b><\/u><\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><u><b>1<\/b><\/u><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><u><b>.-<\/b><\/u><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\">Desde el Grupo Municipal del Partido Popular <\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><b>la protecci\u00f3n del medioambiente y la mejora de nuestros ecosistemas ha sido una m\u00e1xima<\/b><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"> desde siempre. Hace apenas un mes denunci\u00e1bamos que se estaban permitiendo la ilegalidad de <\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><b>verter aguas fecales al rio Tur\u00f3n<\/b><\/span><\/span> <span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><b>ante la pasibilidad del Equipo de Gobierno<\/b><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\">, que, a pesar de la denuncia realizada por este Grupo, <\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><b>voto en contra de intentar solucionar el problema <\/b><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\">en el \u00faltimo Pleno realizado. Ejemplo claro de lo que es preocuparse verdaderamente por el medioambiente y qui\u00e9n simplemente lo lucen ancl\u00e1ndose en una falsa ideolog\u00eda. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"> Seg\u00fan hemos visto en las ultimas semana ha surgido una problem\u00e1tica ante la posible calidad del aire de nuestro Concejo, el cual, por el momento cumple todos los par\u00e1metros que nos proporciona las pocas estaciones medidoras (1 del principado y 2 de empresas privadas) que dispone el Concejo, infraestructuras insuficientes para un Concejo tan extenso. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"> Ante la falta de capacidad de nuestro Equipo de Gobierno para resolver problemas, qued\u00e1ndose \u00fanicamente en las formas de los problemas, sin tener capacidad para entrar en el fondo de estos, desde el Grupo Popular <\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><b>solicitamos que se cree e implante un Plan de Calidad de aire del Concejo de Mieres como soluci\u00f3n a toda esta problem\u00e1tica generada<\/b><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\">. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\">Si bien el Plan se centra en establecer medidas relacionadas con la calidad del aire, es conocida la existencia de sinergias claras entre las actuaciones orientadas a mejorar la calidad del aire y aquellas encaminadas a combatir el cambio clim\u00e1tico. Por tanto, se tratar\u00eda de un documento que permitir\u00eda avanzar al Concejo de Mieres en calidad, habitabilidad y sobre todo en modernidad.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\">Dicho plan puede contener desde Informaci\u00f3n, sensibilizaci\u00f3n y participaci\u00f3n en la mejora de la calidad del aire del municipio por parte de la ciudadan\u00eda, mejora de la movilidad, promoci\u00f3n de modos de transporte alternativos, subvenciones, ayudas, uso de combustibles de bajas emisiones e incluso mejoras de la eficiencia energ\u00e9tica en la edificaci\u00f3n y la gesti\u00f3n municipal. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><b>Consideramos que el recorrido de dicho Plan deber\u00eda de partir de un primer diagn\u00f3stico de la calidad del aire del municipio, pasando por definir unos objetivos y mejoras y por \u00faltimo definiendo como va a ser el seguimiento del Plan<\/b><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\">, consideramos que de esta manera obtendr\u00edamos una gran mejora para nuestros vecinos y nuestro medioambiente. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><b>Podemos seguir<\/b><\/span><\/span> <span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><b>hablando de lo que entra<\/b><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"> o no dentro de nuestras empresas, pero <\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><b>lo que debemos de controlar y exigir que se cumpla la legislaci\u00f3n es lo que salga<\/b><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\">, vigilar lo que se emite por las empresas que realmente es lo que nos llega a todos los vecinos. Creemos que con este Plan el Ayuntamiento de Mieres se convertir\u00eda en uno de los primeros y m\u00e1s modernos ayuntamientos de Asturias en protecci\u00f3n del medioambiente. <\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante las pol\u00e9micas surgidas en las \u00faltimas semanas en el Concejo: El Grupo Municipal del Partido Popular solicita que se cree un PLAN DE CALIDAD DE AIRE para el Concejo de Mieres. Dicho Plan ha de contener mejoras de control de la calidad del aire as\u00ed como mejoras de la informaci\u00f3n, participaci\u00f3n y difusi\u00f3n ante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2651,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,6],"tags":[31,125],"class_list":["post-2650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caudal","category-noticias","tag-mieres","tag-pp-mieres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PP MIERES solicita que se cree un PLAN DE CALIDAD DE AIRE -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PP MIERES solicita que se cree un PLAN DE CALIDAD DE AIRE -\" \/>\n<meta property=\"og:description\" content=\"Ante las pol\u00e9micas surgidas en las \u00faltimas semanas en el Concejo: El Grupo Municipal del Partido Popular solicita que se cree un PLAN DE CALIDAD DE AIRE para el Concejo de Mieres. Dicho Plan ha de contener mejoras de control de la calidad del aire as\u00ed como mejoras de la informaci\u00f3n, participaci\u00f3n y difusi\u00f3n ante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-14T12:02:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/Como-se-mide-la-calidad-del-aire-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/14\\\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/14\\\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"PP MIERES solicita que se cree un PLAN DE CALIDAD DE AIRE\",\"datePublished\":\"2021-05-14T12:02:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/14\\\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\\\/\"},\"wordCount\":570,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/14\\\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Como-se-mide-la-calidad-del-aire-2.jpg\",\"keywords\":[\"mieres\",\"PP MIERES\"],\"articleSection\":[\"Caudal\",\"CM NEWS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/14\\\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/14\\\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/14\\\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\\\/\",\"name\":\"PP MIERES solicita que se cree un PLAN DE CALIDAD DE AIRE -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/14\\\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/14\\\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Como-se-mide-la-calidad-del-aire-2.jpg\",\"datePublished\":\"2021-05-14T12:02:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/14\\\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/14\\\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/14\\\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Como-se-mide-la-calidad-del-aire-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Como-se-mide-la-calidad-del-aire-2.jpg\",\"width\":1200,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/14\\\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PP MIERES solicita que se cree un PLAN DE CALIDAD DE AIRE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PP MIERES solicita que se cree un PLAN DE CALIDAD DE AIRE -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/","og_locale":"es_ES","og_type":"article","og_title":"PP MIERES solicita que se cree un PLAN DE CALIDAD DE AIRE -","og_description":"Ante las pol\u00e9micas surgidas en las \u00faltimas semanas en el Concejo: El Grupo Municipal del Partido Popular solicita que se cree un PLAN DE CALIDAD DE AIRE para el Concejo de Mieres. Dicho Plan ha de contener mejoras de control de la calidad del aire as\u00ed como mejoras de la informaci\u00f3n, participaci\u00f3n y difusi\u00f3n ante [&hellip;]","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/","article_published_time":"2021-05-14T12:02:58+00:00","og_image":[{"width":1200,"height":700,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/Como-se-mide-la-calidad-del-aire-2.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"PP MIERES solicita que se cree un PLAN DE CALIDAD DE AIRE","datePublished":"2021-05-14T12:02:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/"},"wordCount":570,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/Como-se-mide-la-calidad-del-aire-2.jpg","keywords":["mieres","PP MIERES"],"articleSection":["Caudal","CM NEWS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/","name":"PP MIERES solicita que se cree un PLAN DE CALIDAD DE AIRE -","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/Como-se-mide-la-calidad-del-aire-2.jpg","datePublished":"2021-05-14T12:02:58+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/Como-se-mide-la-calidad-del-aire-2.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/Como-se-mide-la-calidad-del-aire-2.jpg","width":1200,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/14\/pp-mieres-solicita-que-se-cree-un-plan-de-calidad-de-aire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"PP MIERES solicita que se cree un PLAN DE CALIDAD DE AIRE"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=2650"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2650\/revisions"}],"predecessor-version":[{"id":2652,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2650\/revisions\/2652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/2651"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=2650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=2650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=2650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}