{"id":2676,"date":"2021-05-17T06:25:57","date_gmt":"2021-05-17T06:25:57","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=2676"},"modified":"2021-05-17T06:25:57","modified_gmt":"2021-05-17T06:25:57","slug":"bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/","title":{"rendered":"BOPA MIERES: Convocatoria de AYUDAS al pago de COMEDOR ESCOLAR"},"content":{"rendered":"<h4 style=\"text-align: center;\">AYUNTAMIENTOS<\/h4>\n<h5 style=\"text-align: center;\">DE MIERES<\/h5>\n<p class=\"subtit-azul\">Anuncio. Extracto de la convocatoria de ayudas al pago de comedor escolar para educaci\u00f3n.<\/p>\n<p>BDNS(Identif.): 562864.<\/p>\n<p>De conformidad con lo previsto en los art\u00edculos 17.3.b y 20.8.a de la Ley 38\/2003, de 17 de noviembre, General de Subvenciones, se publica el extracto de la convocatoria cuyo texto completo puede consultarse en la Base de Datos Nacional de Subvenciones (https:\/\/www.infosubvenciones.es\/bdnstrans\/GE\/es\/convocatoria\/562864).<\/p>\n<p>Convocatoria de ayudas al pago de comedor escolar para Educaci\u00f3n Infantil y Primaria para el curso 2021\/22.<\/p>\n<p>1) El objeto de la presente convocatoria es la regulaci\u00f3n del sistema de concesi\u00f3n de ayudas econ\u00f3micas destinadas al abono de comedor escolar para el alumnado escolarizado en Educaci\u00f3n Infantil y Educaci\u00f3n Primaria, tanto en Centros p\u00fablicos, como concertados del Municipio de Mieres que dispongan de este servicio en el curso 2021\/2022.<\/p>\n<p>2) La convocatoria se rige por las Bases reguladoras de Ayudas al pago de comedor escolar para Educaci\u00f3n Infantil y Primaria publicadas en el Bolet\u00edn Oficial del Principado de Asturias (BOPA) de 5 de agosto de 2020.<\/p>\n<p>3) Lugar y plazo de presentaci\u00f3n de solicitudes.<\/p>\n<p>Las solicitudes habr\u00e1n de presentarse debidamente cumplimentadas en el Registro de entrada del Ayuntamiento de Mieres, o en cualquiera de los lugares previstos en la Ley de Procedimiento Administrativo de las Administraciones P\u00fablicas (Ley 39\/2015 de 1 de octubre).<\/p>\n<p>El plazo de presentaci\u00f3n de solicitudes ser\u00e1 de 15 d\u00edas naturales desde la publicaci\u00f3n de esta convocatoria en el BOPA.<\/p>\n<p>4) La solicitud se presentar\u00e1 en modelo normalizado (disponible en la web, en el Registro Municipal y en la Oficina de Informaci\u00f3n Juvenil), acompa\u00f1ada de la documentaci\u00f3n que se especifica en el art\u00edculo 2 de las Bases reguladoras.<\/p>\n<p>5) La cuant\u00eda global de la presente convocatoria para el curso 2021\/2022 asciende a 80.000 \u20ac.<\/p>\n<p>Mieres, a 6 de mayo de 2021.\u2014El Concejal Delegado de Servicios a la Ciudadan\u00eda.\u2014C\u00f3d. 2021-04816.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AYUNTAMIENTOS DE MIERES Anuncio. Extracto de la convocatoria de ayudas al pago de comedor escolar para educaci\u00f3n. BDNS(Identif.): 562864. De conformidad con lo previsto en los art\u00edculos 17.3.b y 20.8.a de la Ley 38\/2003, de 17 de noviembre, General de Subvenciones, se publica el extracto de la convocatoria cuyo texto completo puede consultarse en la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45,7,6],"tags":[130,161,31],"class_list":["post-2676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayudas","category-caudal","category-noticias","tag-bopa","tag-comedor-escolar","tag-mieres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BOPA MIERES: Convocatoria de AYUDAS al pago de COMEDOR ESCOLAR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BOPA MIERES: Convocatoria de AYUDAS al pago de COMEDOR ESCOLAR\" \/>\n<meta property=\"og:description\" content=\"AYUNTAMIENTOS DE MIERES Anuncio. Extracto de la convocatoria de ayudas al pago de comedor escolar para educaci\u00f3n. BDNS(Identif.): 562864. De conformidad con lo previsto en los art\u00edculos 17.3.b y 20.8.a de la Ley 38\/2003, de 17 de noviembre, General de Subvenciones, se publica el extracto de la convocatoria cuyo texto completo puede consultarse en la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-17T06:25:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/comedor-escolar-1-kIZC-1200x630@abc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1119\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/17\\\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/17\\\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"BOPA MIERES: Convocatoria de AYUDAS al pago de COMEDOR ESCOLAR\",\"datePublished\":\"2021-05-17T06:25:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/17\\\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\\\/\"},\"wordCount\":327,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/17\\\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/comedor-escolar-1-kIZC-1200x630@abc.jpg\",\"keywords\":[\"BOPA\",\"COMEDOR ESCOLAR\",\"mieres\"],\"articleSection\":[\"AYUDAS SOCIALES Y ECONOMICAS\",\"Caudal\",\"CM NEWS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/17\\\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/17\\\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/17\\\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\\\/\",\"name\":\"BOPA MIERES: Convocatoria de AYUDAS al pago de COMEDOR ESCOLAR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/17\\\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/17\\\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/comedor-escolar-1-kIZC-1200x630@abc.jpg\",\"datePublished\":\"2021-05-17T06:25:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/17\\\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/17\\\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/17\\\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/comedor-escolar-1-kIZC-1200x630@abc.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/comedor-escolar-1-kIZC-1200x630@abc.jpg\",\"width\":1119,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/05\\\/17\\\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BOPA MIERES: Convocatoria de AYUDAS al pago de COMEDOR ESCOLAR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BOPA MIERES: Convocatoria de AYUDAS al pago de COMEDOR ESCOLAR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/","og_locale":"es_ES","og_type":"article","og_title":"BOPA MIERES: Convocatoria de AYUDAS al pago de COMEDOR ESCOLAR","og_description":"AYUNTAMIENTOS DE MIERES Anuncio. Extracto de la convocatoria de ayudas al pago de comedor escolar para educaci\u00f3n. BDNS(Identif.): 562864. De conformidad con lo previsto en los art\u00edculos 17.3.b y 20.8.a de la Ley 38\/2003, de 17 de noviembre, General de Subvenciones, se publica el extracto de la convocatoria cuyo texto completo puede consultarse en la [&hellip;]","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/","article_published_time":"2021-05-17T06:25:57+00:00","og_image":[{"width":1119,"height":630,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/comedor-escolar-1-kIZC-1200x630@abc.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"BOPA MIERES: Convocatoria de AYUDAS al pago de COMEDOR ESCOLAR","datePublished":"2021-05-17T06:25:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/"},"wordCount":327,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/comedor-escolar-1-kIZC-1200x630@abc.jpg","keywords":["BOPA","COMEDOR ESCOLAR","mieres"],"articleSection":["AYUDAS SOCIALES Y ECONOMICAS","Caudal","CM NEWS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/","name":"BOPA MIERES: Convocatoria de AYUDAS al pago de COMEDOR ESCOLAR","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/comedor-escolar-1-kIZC-1200x630@abc.jpg","datePublished":"2021-05-17T06:25:57+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/comedor-escolar-1-kIZC-1200x630@abc.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/05\/comedor-escolar-1-kIZC-1200x630@abc.jpg","width":1119,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/05\/17\/bopa-mieres-convocatoria-de-ayudas-al-pago-de-comedor-escolar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"BOPA MIERES: Convocatoria de AYUDAS al pago de COMEDOR ESCOLAR"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=2676"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2676\/revisions"}],"predecessor-version":[{"id":2678,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2676\/revisions\/2678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/2677"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=2676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=2676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=2676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}