{"id":2974,"date":"2021-06-21T12:21:57","date_gmt":"2021-06-21T12:21:57","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=2974"},"modified":"2021-06-21T12:21:57","modified_gmt":"2021-06-21T12:21:57","slug":"las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/","title":{"rendered":"Las asociaciones dicen que 2.500 alegaciones por la t\u00e9rmica \u201cpesan m\u00e1s que una encuesta\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\">Tras conocerse el sondeo de Hunosa que afirma que, de forma mayoritaria (84%), los mierenses apoyan el proyecto de conversi\u00f3n de la t\u00e9rmica de La Pereda, que pasar\u00e1 a utilizar biomasa y un porcentaje reducido de Combustible S\u00f3lido Recuperado (CSR), la respuesta de los colectivos ciudadanos no se ha hecho esperar: \u201cM\u00e1s de 2.500 alegaciones contra el plan pesan m\u00e1s que una encuesta de 400 entrevistas\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-2975\" src=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/06\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0-1024x438.jpg\" alt=\"\" width=\"640\" height=\"274\" srcset=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/06\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0-1024x438.jpg 1024w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/06\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0-300x128.jpg 300w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/06\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0-768x329.jpg 768w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/06\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0.jpg 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">As\u00ed de claro se manifest\u00f3 ayer Miguel \u00c1ngel Mart\u00edn, de la asociaci\u00f3n vecinal \u201cLa Fuente\u201d, del pueblo de La Rebollada, quien asegur\u00f3 que \u201cponer la palabra \u2018bio\u2019 por delante no hace respetuoso con el medio ambiente la basura que pretenden quemar\u201d. Y es que los colectivos contrarios al proyecto de transformaci\u00f3n de la central consideran el CSR como basura. Eso a pesar de que hasta el vicepresidente y consejero de Administraci\u00f3n Auton\u00f3mica, Medio Ambiente y Cambio Clim\u00e1tico, Juan Cofi\u00f1o, descart\u00f3 que La Pereda vaya a quemar \u201cbasura\u201d, consider\u00e1ndolo \u201cuna simplificaci\u00f3n, porque el CSR no es un residuo, requiere m\u00e1s matices y conocimiento\u201d.<\/p>\n<p style=\"text-align: justify;\">Miguel \u00c1ngel Mart\u00edn critic\u00f3 el estudio de opini\u00f3n de Hunosa que, en su opini\u00f3n, \u201ces una muestra lo suficientemente peque\u00f1a para no representar al concejo y adem\u00e1s no sabemos c\u00f3mo se redact\u00f3\u201d. De este modo, \u201cnos preguntamos si realmente han hecho una encuesta en la que expliquen la composici\u00f3n \u2018bio\u2019 de la que hablan y en donde abiertamente aclaren la procedencia del CSR y el tipo de combustible que necesitan para conseguir la potencia calor\u00edfica que necesitan\u201d. Para el representante vecinal, \u201cel CSR es basura, con una composici\u00f3n media de un 31% de pl\u00e1sticos, un 13% de papel y cart\u00f3n, el 12% de madera, un 14% de textiles y el 30% de otros materiales\u201d. Es la composici\u00f3n media de los CSR en Europa, afirma. Y para mejorar la potencia calor\u00edfica, \u201cnada mejor que el pl\u00e1stico\u201d.<\/p>\n<p style=\"text-align: justify;\">El proyecto de transformaci\u00f3n de la t\u00e9rmica de La Pereda tiene un presupuesto de casi 40 millones de euros . El plan asegurar\u00eda el mantenimiento de los 73 empleos que ahora da la t\u00e9rmica, pero no s\u00f3lo eso, sino que podr\u00eda llegar a crear en torno a 200 puestos de trabajo. El punto m\u00e1s pol\u00e9mico es la utilizaci\u00f3n de CSR, que ser\u00eda una cantidad muy limitada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras conocerse el sondeo de Hunosa que afirma que, de forma mayoritaria (84%), los mierenses apoyan el proyecto de conversi\u00f3n de la t\u00e9rmica de La Pereda, que pasar\u00e1 a utilizar biomasa y un porcentaje reducido de Combustible S\u00f3lido Recuperado (CSR), la respuesta de los colectivos ciudadanos no se ha hecho esperar: \u201cM\u00e1s de 2.500 alegaciones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2975,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,6],"tags":[],"class_list":["post-2974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caudal","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las asociaciones dicen que 2.500 alegaciones por la t\u00e9rmica \u201cpesan m\u00e1s que una encuesta\u201d -<\/title>\n<meta name=\"description\" content=\"Las asociaciones cuestionan el estudio de opini\u00f3n de Hunosa y piden que aclare la procedencia del CSR que se utilizar\u00e1 en la planta\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las asociaciones dicen que 2.500 alegaciones por la t\u00e9rmica \u201cpesan m\u00e1s que una encuesta\u201d -\" \/>\n<meta property=\"og:description\" content=\"Las asociaciones cuestionan el estudio de opini\u00f3n de Hunosa y piden que aclare la procedencia del CSR que se utilizar\u00e1 en la planta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-21T12:21:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/06\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"548\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/06\\\/21\\\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/06\\\/21\\\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"Las asociaciones dicen que 2.500 alegaciones por la t\u00e9rmica \u201cpesan m\u00e1s que una encuesta\u201d\",\"datePublished\":\"2021-06-21T12:21:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/06\\\/21\\\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\\\/\"},\"wordCount\":411,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/06\\\/21\\\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0.jpg\",\"articleSection\":[\"Caudal\",\"CM NEWS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/06\\\/21\\\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/06\\\/21\\\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/06\\\/21\\\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\\\/\",\"name\":\"Las asociaciones dicen que 2.500 alegaciones por la t\u00e9rmica \u201cpesan m\u00e1s que una encuesta\u201d -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/06\\\/21\\\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/06\\\/21\\\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0.jpg\",\"datePublished\":\"2021-06-21T12:21:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"description\":\"Las asociaciones cuestionan el estudio de opini\u00f3n de Hunosa y piden que aclare la procedencia del CSR que se utilizar\u00e1 en la planta\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/06\\\/21\\\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/06\\\/21\\\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/06\\\/21\\\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0.jpg\",\"width\":1280,\"height\":548},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/06\\\/21\\\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las asociaciones dicen que 2.500 alegaciones por la t\u00e9rmica \u201cpesan m\u00e1s que una encuesta\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las asociaciones dicen que 2.500 alegaciones por la t\u00e9rmica \u201cpesan m\u00e1s que una encuesta\u201d -","description":"Las asociaciones cuestionan el estudio de opini\u00f3n de Hunosa y piden que aclare la procedencia del CSR que se utilizar\u00e1 en la planta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/","og_locale":"es_ES","og_type":"article","og_title":"Las asociaciones dicen que 2.500 alegaciones por la t\u00e9rmica \u201cpesan m\u00e1s que una encuesta\u201d -","og_description":"Las asociaciones cuestionan el estudio de opini\u00f3n de Hunosa y piden que aclare la procedencia del CSR que se utilizar\u00e1 en la planta","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/","article_published_time":"2021-06-21T12:21:57+00:00","og_image":[{"width":1280,"height":548,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/06\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"Las asociaciones dicen que 2.500 alegaciones por la t\u00e9rmica \u201cpesan m\u00e1s que una encuesta\u201d","datePublished":"2021-06-21T12:21:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/"},"wordCount":411,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/06\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0.jpg","articleSection":["Caudal","CM NEWS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/","name":"Las asociaciones dicen que 2.500 alegaciones por la t\u00e9rmica \u201cpesan m\u00e1s que una encuesta\u201d -","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/06\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0.jpg","datePublished":"2021-06-21T12:21:57+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"description":"Las asociaciones cuestionan el estudio de opini\u00f3n de Hunosa y piden que aclare la procedencia del CSR que se utilizar\u00e1 en la planta","breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/06\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/06\/77eb7af2-3c1e-4b4e-9bba-f5b6160090e6_21-9-aspect-ratio_default_0.jpg","width":1280,"height":548},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/06\/21\/las-asociaciones-dicen-que-2-500-alegaciones-por-la-termica-pesan-mas-que-una-encuesta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"Las asociaciones dicen que 2.500 alegaciones por la t\u00e9rmica \u201cpesan m\u00e1s que una encuesta\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=2974"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2974\/revisions"}],"predecessor-version":[{"id":2976,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/2974\/revisions\/2976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/2975"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=2974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=2974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=2974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}