{"id":3936,"date":"2021-11-27T15:43:38","date_gmt":"2021-11-27T15:43:38","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=3936"},"modified":"2021-11-27T15:43:38","modified_gmt":"2021-11-27T15:43:38","slug":"valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/","title":{"rendered":"Valnal\u00f3n articula una red para despertar vocaciones cient\u00edficas entre el alumnado"},"content":{"rendered":"<p style=\"text-align: justify;\">Despertar las vocaciones tecnol\u00f3gicas entre el alumnado y promover la relaci\u00f3n con centros de investigaci\u00f3n, empresas, instituciones p\u00fablicas y privadas. Esos son los objetivos de la Red Asturias4STEAM, impulsada por la Ciudad Tecnol\u00f3gica de Valnal\u00f3n, que fue presentada ayer en el espacio Arkuos de Langreo. Para dar cuenta del respaldo de la red, el acto cont\u00f3 con la presencia del director general del Cluster TIC, Enrique J\u00e1imez Falag\u00e1n; el director del Centro de Investigaci\u00f3n en Nanomateriales y Nanotecnolog\u00eda (CINN), con sede en el edificio tecnol\u00f3gico del pozo Entrego, Adolfo Fern\u00e1ndez Vald\u00e9s; y Cristina Coll Fueyo, profesora de Centro Integrado de Formaci\u00f3n Profesional de Comunicaci\u00f3n, Imagen y Sonido (CIFP Cislan), ubicado en Langreo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3937\" src=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0-1024x576.jpg\" alt=\"\" width=\"640\" height=\"360\" srcset=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0-1024x576.jpg 1024w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0-300x169.jpg 300w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0-768x432.jpg 768w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">Durante la jornada se reivindic\u00f3 la necesidad de fomentar la educaci\u00f3n STEAM, basada en la ciencia, la tecnolog\u00eda, la ingenier\u00eda, el arte y las matem\u00e1ticas; y hacerlo en red. \u201cSon cinco claves del presente continuo que es necesario promover, impulsando las vocaciones cient\u00edfico-tecnol\u00f3gicas desde la educaci\u00f3n hasta alcanzar la etapa laboral, creando experiencias relevantes que permitan a las personas ampliar sus horizontes\u201d, explic\u00f3 Jos\u00e9 Vega, de Valnal\u00f3n. Para lograr este fin \u201ctenemos que implicar a los centros de investigaci\u00f3n, instituciones p\u00fablicas y privadas para que las l\u00edneas de actuaci\u00f3n lleguen al alumnado, independientemente de su grupo de edad\u201d.<\/p>\n<p style=\"text-align: justify;\">La propuesta fue recibida de buen grado por parte del director del CINN, quien asegur\u00f3 que \u201ces necesario contar con una red que ponga en contacto a todo tipo de organismos, ya que hay multitud de actores y tenemos un papel fundamental para fomentar las vocaciones STEAM\u201d. Fern\u00e1ndez Vald\u00e9s aprovech\u00f3 para explicar que el centro que dirige \u201ces receptor de personas con este tipo de vocaciones, pero no s\u00f3lo eso, tambi\u00e9n recibimos visitas de centros escolares e interactuamos con ellos para fomentar las vocaciones cient\u00edficas, ya que somos los primeros interesados en que se desarrollen\u201d.<\/p>\n<p style=\"text-align: justify;\">Desde el Cluster TIC valoran \u201cla creaci\u00f3n de un ecosistema en Asturias para el fomento de las vocaciones STEAM\u201d, como apunt\u00f3 J\u00e1imez Falag\u00e1n. En el pasado ya colaboraron con Valnal\u00f3n para la elaboraci\u00f3n de una gu\u00eda de colaboraci\u00f3n entre empresas y centros de formaci\u00f3n en FP. \u201cLa colaboraci\u00f3n entre empresas y los centros se realizaba hasta entonces de una forma voluntarista y con la gu\u00eda lanzamos un protocolo de c\u00f3mo tender puentes y por qu\u00e9 colaborar con este tipo de centros\u201d, destac\u00f3. La respuesta a esta \u00faltima pregunta es clara: \u201cCaptar talento, nuestro sector tiene una alta demanda de profesionales\u201d. El director del Cluster TIC aludi\u00f3 tambi\u00e9n al desarrollo de proyectos de innovaci\u00f3n con estos centros \u201cque son una manera de acercar al alumnado y profesorado a la empresa\u201d. Por \u00faltimo, abog\u00f3 por desarrollar \u201calianzas de colaboraci\u00f3n de largo plazo, y lo m\u00e1s l\u00f3gico es que nuestro cluster o Valnal\u00f3n sean los canales a los que acudir cuando se quiere colaborar con las empresas\u201d.<\/p>\n<p style=\"text-align: justify;\">Un buen ejemplo de la colaboraci\u00f3n que ya existe entre los centros de FP y las empresas se da en el Cislan. Coll Fueyo explic\u00f3 que , por una parte, \u201ctenemos la formaci\u00f3n del profesorado, que incluye estancias de los docentes en las empresas, pero tambi\u00e9n acuerdos de colaboraci\u00f3n con otras entidades para que nuestros alumnos tengan una experiencia de trabajo real\u201d. En este sentido, la docente aludi\u00f3 a la formaci\u00f3n en los centros de trabajo, \u201cunas pr\u00e1cticas que son muy \u00fatiles porque a veces se consiguen contratos y, en el caso de la empresa, estos captan talento\u201d.<\/p>\n<p style=\"text-align: justify;\">La red presentada ayer forma parte del proyecto \u201cTeam STEAM Asturias\u201d, subvencionado por la Consejer\u00eda de Ciencia, Innovaci\u00f3n y Universidad dentro de las actuaciones de promoci\u00f3n de la I+D+I del Principado de Asturias. Esta apuesta por el impulso de las vocaciones STEAM procede de la experiencia acumulada por la Red Emprendedora de Valnal\u00f3n, que lleva en funcionamiento desde 2013 y donde han participado m\u00e1s de 300 entidades. Aqu\u00ed se enmarca la impartici\u00f3n de charlas, acciones de mentorizaci\u00f3n, visitas y retos con estudiantes. Asimismo, desde Valnal\u00f3n se ha editado la ya citada gu\u00eda pr\u00e1ctica a la que aludi\u00f3 el director del Cluster TIC. Tambi\u00e9n se est\u00e1n realizando acciones de formaci\u00f3n del profesorado en colaboraci\u00f3n con los Centros de Profesorado y de Recursos (CPR) del Principado. Y, por \u00faltimo, se ha creado el Grupo de Lectura de Did\u00e1ctica de las Ciencias para reivindicar la tertulia y el di\u00e1logo. Este grupo es, explican desde Valnal\u00f3n, \u201cuna herramienta para la construcci\u00f3n de conocimiento colectivo\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>LNE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despertar las vocaciones tecnol\u00f3gicas entre el alumnado y promover la relaci\u00f3n con centros de investigaci\u00f3n, empresas, instituciones p\u00fablicas y privadas. Esos son los objetivos de la Red Asturias4STEAM, impulsada por la Ciudad Tecnol\u00f3gica de Valnal\u00f3n, que fue presentada ayer en el espacio Arkuos de Langreo. Para dar cuenta del respaldo de la red, el acto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,8],"tags":[],"class_list":["post-3936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-nalon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Valnal\u00f3n articula una red para despertar vocaciones cient\u00edficas entre el alumnado - cm news<\/title>\n<meta name=\"description\" content=\"La iniciativa busca potenciar las relaciones de los estudiantes con centros de investigaci\u00f3n, empresas e instituciones p\u00fablicas y privadas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valnal\u00f3n articula una red para despertar vocaciones cient\u00edficas entre el alumnado - cm news\" \/>\n<meta property=\"og:description\" content=\"La iniciativa busca potenciar las relaciones de los estudiantes con centros de investigaci\u00f3n, empresas e instituciones p\u00fablicas y privadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-27T15:43:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/27\\\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/27\\\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"Valnal\u00f3n articula una red para despertar vocaciones cient\u00edficas entre el alumnado\",\"datePublished\":\"2021-11-27T15:43:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/27\\\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\\\/\"},\"wordCount\":815,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/27\\\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0.jpg\",\"articleSection\":[\"CM NEWS\",\"Nal\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/27\\\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/27\\\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/27\\\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\\\/\",\"name\":\"Valnal\u00f3n articula una red para despertar vocaciones cient\u00edficas entre el alumnado - cm news\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/27\\\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/27\\\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0.jpg\",\"datePublished\":\"2021-11-27T15:43:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"description\":\"La iniciativa busca potenciar las relaciones de los estudiantes con centros de investigaci\u00f3n, empresas e instituciones p\u00fablicas y privadas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/27\\\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/27\\\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/27\\\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/27\\\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valnal\u00f3n articula una red para despertar vocaciones cient\u00edficas entre el alumnado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valnal\u00f3n articula una red para despertar vocaciones cient\u00edficas entre el alumnado - cm news","description":"La iniciativa busca potenciar las relaciones de los estudiantes con centros de investigaci\u00f3n, empresas e instituciones p\u00fablicas y privadas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/","og_locale":"es_ES","og_type":"article","og_title":"Valnal\u00f3n articula una red para despertar vocaciones cient\u00edficas entre el alumnado - cm news","og_description":"La iniciativa busca potenciar las relaciones de los estudiantes con centros de investigaci\u00f3n, empresas e instituciones p\u00fablicas y privadas.","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/","article_published_time":"2021-11-27T15:43:38+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"Valnal\u00f3n articula una red para despertar vocaciones cient\u00edficas entre el alumnado","datePublished":"2021-11-27T15:43:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/"},"wordCount":815,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0.jpg","articleSection":["CM NEWS","Nal\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/","name":"Valnal\u00f3n articula una red para despertar vocaciones cient\u00edficas entre el alumnado - cm news","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0.jpg","datePublished":"2021-11-27T15:43:38+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"description":"La iniciativa busca potenciar las relaciones de los estudiantes con centros de investigaci\u00f3n, empresas e instituciones p\u00fablicas y privadas.","breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/1aba718d-520f-4cc6-a19d-416453a23d53_16-9-discover-aspect-ratio_default_0.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/27\/valnalon-articula-una-red-para-despertar-vocaciones-cientificas-entre-el-alumnado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"Valnal\u00f3n articula una red para despertar vocaciones cient\u00edficas entre el alumnado"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/3936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=3936"}],"version-history":[{"count":2,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/3936\/revisions"}],"predecessor-version":[{"id":3939,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/3936\/revisions\/3939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/3937"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=3936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=3936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=3936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}