{"id":3953,"date":"2021-11-29T15:19:30","date_gmt":"2021-11-29T15:19:30","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=3953"},"modified":"2021-11-29T15:19:30","modified_gmt":"2021-11-29T15:19:30","slug":"descontento-generalizado-en-el-mercado-de-abastos-de-mieres","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/","title":{"rendered":"Descontento generalizado en el Mercado de Abastos de Mieres"},"content":{"rendered":"<p style=\"text-align: justify;\">La centenaria plaza de abastos de Mieres carece \u00faltimamente del vigor de anta\u00f1o. El popular mercado cubierto fue inaugurado en 1907 y actualmente se encuentra bastante deteriorado. Pero los achaques, en este caso, no tiene relaci\u00f3n directa con los muchos a\u00f1os de vida. Los comerciantes est\u00e1n al borde de la crispaci\u00f3n. Denuncian que desde que el Ayuntamiento decidiera cerrar al tr\u00e1fico las calles colindantes los establecimiento han perdido \u201cm\u00e1s del cincuenta por ciento de las ventas\u201d. Algunos hablan de hasta una ca\u00edda del 60 por ciento. Las quejas se trasladan tambi\u00e9n a los negocios del entorno. La tormenta desata de fondo truenos por el abandono de las dependencias.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3954\" src=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/Mercado-Municipal-de-Abastos-Mieres-del-Camin.jpg\" alt=\"\" width=\"583\" height=\"386\" srcset=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/Mercado-Municipal-de-Abastos-Mieres-del-Camin.jpg 583w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/Mercado-Municipal-de-Abastos-Mieres-del-Camin-300x199.jpg 300w\" sizes=\"auto, (max-width: 583px) 100vw, 583px\" \/><\/p>\n<p style=\"text-align: justify;\">Son dos los reproches principales de los arrendatarios de los puestos municipales. Por un lado critican el abandono de las instalaciones, con falta de mantenimiento y limpieza, y por otro sostienen que la peatonalizaci\u00f3n de este espacio urbano ha \u201cespantado\u201d a una parte muy importante de clientela. \u201cSufrimos una total dejadez y abandono\u201d, se\u00f1ala Geli Su\u00e1rez, conocida pescadera de la plaza. \u201cLas paredes est\u00e1n llenas de desconchados, hay telara\u00f1as por todos sitios y los cristales no se limpian nunca\u201d, remarca Marina Ord\u00f3\u00f1ez. \u201cY luego est\u00e1n las palomas. Adem\u00e1s pueden pasar meses para que se limpie el suelo, m\u00e1s all\u00e1 de pasar la manguera\u201d, indica Renata Canis.<\/p>\n<p style=\"text-align: justify;\">Los comerciantes de la plaza est\u00e1n muy molestos con el Ayuntamiento . Ponen como ejemplo de la \u201cdesidia\u201d que perciben el estado en que se encuentran los aseos del equipamiento. En concreto, denuncian que el urinario y los lavabos que habitualmente utilizan las personas con alg\u00fan tipo de discapacidad llevan un mes pendientes de una actuaci\u00f3n de arreglo tras sufrir la sala graves desperfectos. \u201cHemos llegado a tener hasta setas dentro de los servicios\u201d, cuenta Tamara Solomando mientras se\u00f1ala el techo indicando las goteras que tiene en su puesto de fruta. \u201cHace dos a\u00f1os cambiamos la cubierta y estaba todo podrido; no hay nada que hacer\u201d.<\/p>\n<p style=\"text-align: justify;\">La plaza de abastos es uno de los rincones m\u00e1s representativos del casco urbano de Mieres. \u201cEs un edificio magn\u00edfico y en Espa\u00f1a hay pocos mercados tan bonitos, pero el abandono es terrible\u201d, se\u00f1alan los profesionales. Actualmente hay unos veinte puestos cerrados. \u201cCasi la mitad\u201d, subraya Marina Ord\u00f3\u00f1ez. Un especial da\u00f1o ha causado a la actividad comercial la decisi\u00f3n del Ayuntamiento de cerrar al tr\u00e1fico las calles Doce de Octubre y Escuela de Capataces, convirtiendo todo el espacio en una gran eje peatonal. La medida se abord\u00f3 inicialmente con car\u00e1cter temporal, para facilitar el tr\u00e1nsito de los viandantes durante la pandemia, pero los planes municipales pasan ahora por abordar una peatonalizaci\u00f3n definitiva. La eliminaci\u00f3n del tr\u00e1fico ha repercutido en la econom\u00eda de estos aut\u00f3nomos. \u201cHemos perdido sobre el cincuenta por ciento de las ventas\u201d, remarca Geli Su\u00e1rez. \u201cAhora pr\u00e1cticamente vivimos del mercado dominical, aunque tambi\u00e9n ha bajado mucho la actividad\u201d, subraya Renata Canis.<\/p>\n<p style=\"text-align: justify;\">Los comerciantes reclaman dos medidas para aliviar su situaci\u00f3n. \u201cPedimos que se deje circular a los coches durante la ma\u00f1ana\u201d, indican. En este sentido, perciben que su petici\u00f3n va contra las demandas de los nuevos tiempos, con directrices europeas que reclaman ciudades peatonales sin autom\u00f3viles. Ahora bien, apuntan que \u201cEuropa tambi\u00e9n exige limpieza y en Mieres brilla por su ausencia\u201d. La segunda medida parece tener poco margen de debate. El sentir general es que el aparcamiento de O\u00f1\u00f3n, construido el a\u00f1o pasado con 300 plazas para facilitar la rotaci\u00f3n, no est\u00e1 cumpliendo con su cometido. \u201cAl final se ha convertido en una gran cochera p\u00fablica, donde algunos vecinos aparcan bloqueado su finalidad dinamizadora\u201d, se\u00f1ala Marina Ord\u00f3\u00f1ez. Los comerciantes demandan al Ayuntamiento alg\u00fan tipo de control sobre el uso de este aparcamiento, el m\u00e1s pr\u00f3ximo a la plaza. El Ayuntamiento lleva varios a\u00f1os planeando una actuaci\u00f3n en la plaza. Los comerciantes piden cambios urgentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La centenaria plaza de abastos de Mieres carece \u00faltimamente del vigor de anta\u00f1o. El popular mercado cubierto fue inaugurado en 1907 y actualmente se encuentra bastante deteriorado. Pero los achaques, en este caso, no tiene relaci\u00f3n directa con los muchos a\u00f1os de vida. Los comerciantes est\u00e1n al borde de la crispaci\u00f3n. Denuncian que desde que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,6],"tags":[],"class_list":["post-3953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caudal","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Descontento generalizado en el Mercado de Abastos de Mieres - cm news<\/title>\n<meta name=\"description\" content=\"Los comerciantes del mercado de Mieres, contra las peatonalizaciones y el abandono: \u201cHemos perdido el 50% de las ventas\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descontento generalizado en el Mercado de Abastos de Mieres - cm news\" \/>\n<meta property=\"og:description\" content=\"Los comerciantes del mercado de Mieres, contra las peatonalizaciones y el abandono: \u201cHemos perdido el 50% de las ventas\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-29T15:19:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/Mercado-Municipal-de-Abastos-Mieres-del-Camin.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"583\" \/>\n\t<meta property=\"og:image:height\" content=\"386\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/29\\\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/29\\\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"Descontento generalizado en el Mercado de Abastos de Mieres\",\"datePublished\":\"2021-11-29T15:19:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/29\\\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\\\/\"},\"wordCount\":688,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/29\\\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Mercado-Municipal-de-Abastos-Mieres-del-Camin.jpg\",\"articleSection\":[\"Caudal\",\"CM NEWS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/29\\\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/29\\\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/29\\\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\\\/\",\"name\":\"Descontento generalizado en el Mercado de Abastos de Mieres - cm news\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/29\\\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/29\\\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Mercado-Municipal-de-Abastos-Mieres-del-Camin.jpg\",\"datePublished\":\"2021-11-29T15:19:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"description\":\"Los comerciantes del mercado de Mieres, contra las peatonalizaciones y el abandono: \u201cHemos perdido el 50% de las ventas\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/29\\\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/29\\\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/29\\\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Mercado-Municipal-de-Abastos-Mieres-del-Camin.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Mercado-Municipal-de-Abastos-Mieres-del-Camin.jpg\",\"width\":583,\"height\":386},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2021\\\/11\\\/29\\\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descontento generalizado en el Mercado de Abastos de Mieres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descontento generalizado en el Mercado de Abastos de Mieres - cm news","description":"Los comerciantes del mercado de Mieres, contra las peatonalizaciones y el abandono: \u201cHemos perdido el 50% de las ventas\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/","og_locale":"es_ES","og_type":"article","og_title":"Descontento generalizado en el Mercado de Abastos de Mieres - cm news","og_description":"Los comerciantes del mercado de Mieres, contra las peatonalizaciones y el abandono: \u201cHemos perdido el 50% de las ventas\u201d.","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/","article_published_time":"2021-11-29T15:19:30+00:00","og_image":[{"width":583,"height":386,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/Mercado-Municipal-de-Abastos-Mieres-del-Camin.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"Descontento generalizado en el Mercado de Abastos de Mieres","datePublished":"2021-11-29T15:19:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/"},"wordCount":688,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/Mercado-Municipal-de-Abastos-Mieres-del-Camin.jpg","articleSection":["Caudal","CM NEWS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/","name":"Descontento generalizado en el Mercado de Abastos de Mieres - cm news","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/Mercado-Municipal-de-Abastos-Mieres-del-Camin.jpg","datePublished":"2021-11-29T15:19:30+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"description":"Los comerciantes del mercado de Mieres, contra las peatonalizaciones y el abandono: \u201cHemos perdido el 50% de las ventas\u201d.","breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/Mercado-Municipal-de-Abastos-Mieres-del-Camin.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2021\/11\/Mercado-Municipal-de-Abastos-Mieres-del-Camin.jpg","width":583,"height":386},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2021\/11\/29\/descontento-generalizado-en-el-mercado-de-abastos-de-mieres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"Descontento generalizado en el Mercado de Abastos de Mieres"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/3953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=3953"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/3953\/revisions"}],"predecessor-version":[{"id":3955,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/3953\/revisions\/3955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/3954"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=3953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=3953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=3953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}