{"id":4352,"date":"2022-02-18T23:42:16","date_gmt":"2022-02-18T23:42:16","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=4352"},"modified":"2022-02-18T23:42:16","modified_gmt":"2022-02-18T23:42:16","slug":"ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/","title":{"rendered":"Ciudadanos exige al Principado que detalle en la Junta sus planes para rehabilitar Bustiello"},"content":{"rendered":"<p style=\"text-align: justify;\">El director general de Patrimonio del Principado, Pablo Le\u00f3n, deber\u00e1 comparecer para explicar los planes del Gobierno regional para el sanatorio, la botica y la escuela de ni\u00f1as del poblado minero de Bustiello, en Mieres. El grupo parlamentario de Ciudadanos, a trav\u00e9s de su portavoz en la Comisi\u00f3n de Cultura, Armando Fern\u00e1ndez, ha pedido la presencia del responsable regional, una propuesta respaldada por la mayor\u00eda de los diputados presentes en la sesi\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4353\" src=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394-1024x438.jpg\" alt=\"\" width=\"640\" height=\"274\" srcset=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394-1024x438.jpg 1024w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394-300x128.jpg 300w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394-768x329.jpg 768w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394.jpg 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">Desde la formaci\u00f3n naranja hab\u00edan solicitado al Gobierno regional que diese cuenta sobre el cumplimiento de la moci\u00f3n en la que se hab\u00eda acordado poner en marcha un plan de rehabilitaci\u00f3n para el enclave mierense, que fue declarado Bien de Inter\u00e9s Cultural en el a\u00f1o 2017. La respuesta, que seg\u00fan se comunic\u00f3 ayer se hab\u00eda tramitado por escrito, no fue suficiente para Ciudadanos, que ahora espera que el propio responsable de Patrimonio sea el que explique sus planes.<\/p>\n<p style=\"text-align: justify;\">Y mientras en la Junta General del Principado se suceden los debates pol\u00edticos, la realidad es que para este 2022 no parece que el Gobierno auton\u00f3mico tenga pensado actuar en el enclave minero. Es lo que se deduce del presupuesto regional, en el que no se contempla ning\u00fan tipo de actuaci\u00f3n estructural. La \u00fanica medida inicialmente prevista es el tapiado de puertas y ventanas para evitar el acceso al interior de las instalaciones, asaltadas sistem\u00e1ticamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director general de Patrimonio del Principado, Pablo Le\u00f3n, deber\u00e1 comparecer para explicar los planes del Gobierno regional para el sanatorio, la botica y la escuela de ni\u00f1as del poblado minero de Bustiello, en Mieres. El grupo parlamentario de Ciudadanos, a trav\u00e9s de su portavoz en la Comisi\u00f3n de Cultura, Armando Fern\u00e1ndez, ha pedido la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4353,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,6],"tags":[],"class_list":["post-4352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caudal","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ciudadanos exige al Principado que detalle en la Junta sus planes para rehabilitar Bustiello - cm news<\/title>\n<meta name=\"description\" content=\"La Comisi\u00f3n de Cultura de la Junta respald\u00f3 una propuesta presentada por Cs en la que se insta a comparecer al director general de Patrimonio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciudadanos exige al Principado que detalle en la Junta sus planes para rehabilitar Bustiello - cm news\" \/>\n<meta property=\"og:description\" content=\"La Comisi\u00f3n de Cultura de la Junta respald\u00f3 una propuesta presentada por Cs en la que se insta a comparecer al director general de Patrimonio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-18T23:42:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"548\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"Ciudadanos exige al Principado que detalle en la Junta sus planes para rehabilitar Bustiello\",\"datePublished\":\"2022-02-18T23:42:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\\\/\"},\"wordCount\":258,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394.jpg\",\"articleSection\":[\"Caudal\",\"CM NEWS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\\\/\",\"name\":\"Ciudadanos exige al Principado que detalle en la Junta sus planes para rehabilitar Bustiello - cm news\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394.jpg\",\"datePublished\":\"2022-02-18T23:42:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"description\":\"La Comisi\u00f3n de Cultura de la Junta respald\u00f3 una propuesta presentada por Cs en la que se insta a comparecer al director general de Patrimonio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394.jpg\",\"width\":1280,\"height\":548},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciudadanos exige al Principado que detalle en la Junta sus planes para rehabilitar Bustiello\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ciudadanos exige al Principado que detalle en la Junta sus planes para rehabilitar Bustiello - cm news","description":"La Comisi\u00f3n de Cultura de la Junta respald\u00f3 una propuesta presentada por Cs en la que se insta a comparecer al director general de Patrimonio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/","og_locale":"es_ES","og_type":"article","og_title":"Ciudadanos exige al Principado que detalle en la Junta sus planes para rehabilitar Bustiello - cm news","og_description":"La Comisi\u00f3n de Cultura de la Junta respald\u00f3 una propuesta presentada por Cs en la que se insta a comparecer al director general de Patrimonio.","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/","article_published_time":"2022-02-18T23:42:16+00:00","og_image":[{"width":1280,"height":548,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"Ciudadanos exige al Principado que detalle en la Junta sus planes para rehabilitar Bustiello","datePublished":"2022-02-18T23:42:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/"},"wordCount":258,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394.jpg","articleSection":["Caudal","CM NEWS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/","name":"Ciudadanos exige al Principado que detalle en la Junta sus planes para rehabilitar Bustiello - cm news","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394.jpg","datePublished":"2022-02-18T23:42:16+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"description":"La Comisi\u00f3n de Cultura de la Junta respald\u00f3 una propuesta presentada por Cs en la que se insta a comparecer al director general de Patrimonio.","breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/35cbe9dc-9725-4f8d-bbdd-9fd59ad69a27_21-9-aspect-ratio_default_0_x856y394.jpg","width":1280,"height":548},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/ciudadanos-exige-al-principado-que-detalle-en-la-junta-sus-planes-para-rehabilitar-bustiello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"Ciudadanos exige al Principado que detalle en la Junta sus planes para rehabilitar Bustiello"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=4352"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4352\/revisions"}],"predecessor-version":[{"id":4354,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4352\/revisions\/4354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/4353"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=4352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=4352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=4352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}