{"id":4355,"date":"2022-02-18T23:44:42","date_gmt":"2022-02-18T23:44:42","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=4355"},"modified":"2022-02-18T23:44:42","modified_gmt":"2022-02-18T23:44:42","slug":"el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/","title":{"rendered":"El gobierno de Mieres porf\u00eda por el grado de Deportes: \u201cPonerlo aqu\u00ed cuesta menos\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\">La llegada de Deportes, la continuidad de Geom\u00e1tica y una integraci\u00f3n de Minas en Mieres sin crear nuevos centros. Esas son, en esencia, las tres alegaciones que el gobierno local de Mieres (IU) ha presentado a la propuesta de Planes Estrat\u00e9gicos de la Universidad de Oviedo dentro del periodo de informaci\u00f3n p\u00fablica abierto por la instituci\u00f3n universitaria. Desde que se anunciara la planificaci\u00f3n del Rector, Ignacio Villaverde, el Ayuntamiento de Mieres se ha mostrado muy cr\u00edtico, cuestiones que ha plasmado en las alegaciones. Eso s\u00ed, si el PP de Mieres ya se hab\u00eda desmarcado de la unidad de acci\u00f3n municipal, ahora el PSOE tambi\u00e9n se muestra molesto al sentir que no ha sido debidamente informado en el proceso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4356\" src=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215-1024x438.jpg\" alt=\"\" width=\"640\" height=\"274\" srcset=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215-1024x438.jpg 1024w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215-300x128.jpg 300w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215-768x329.jpg 768w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215.jpg 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">El primer punto que se plantea desde Mieres trata sobre el Grado de Ciencias de la Actividad F\u00edsica y del Deporte, que Villaverde anunci\u00f3 que ir\u00eda para Oviedo. Desde el Ayuntamiento indican que \u201cen su propuesta la Universidad no aporta informes de costes ni auditor\u00edas de espacios, como tampoco la previsi\u00f3n del gasto que supondr\u00e1 la necesaria reorganizaci\u00f3n de espacios e instalaciones que requerir\u00e1 implantar este grado en Llamaquique\u201d. El Consistorio mierense entiende que en el documento de la Universidad \u201cel \u00fanico argumento que se aporta para fundamentar la propuesta son los costes de locomoci\u00f3n y desplazamiento del profesorado, sin plantear tampoco un estudio de costes o una estimaci\u00f3n\u201d. \u201cA la vista de estas circunstancias, parece evidente que no se puede afirmar que la propuesta sea la \u00fanica viable ni tampoco la m\u00e1s eficiente\u201d, indican las alegaciones presentadas, para subrayar que \u201cel Campus de Mieres dispone de las infraestructuras deportivas, aulas y laboratorios necesarios para este Grado por lo que el coste de su implantaci\u00f3n, desde este \u00e1mbito, es notablemente menor\u201d.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, desde Mieres destacan la \u201cplena colaboraci\u00f3n del Ayuntamiento para facilitar cualesquiera instalaciones municipales deportivas necesarias\u201d, al tiempo que indican la cercan\u00eda de las estaciones de esqu\u00ed asturianas. \u201cLa opci\u00f3n de Mieres no requiere costosas operaciones de traslado y equipamiento de nuevos edificios como requisito previo para su implantaci\u00f3n, lo que supone un menor gasto p\u00fablico y es la opci\u00f3n que menor tiempo requiere para su puesta en marcha\u201d, prosiguen desde Mieres.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: LNE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La llegada de Deportes, la continuidad de Geom\u00e1tica y una integraci\u00f3n de Minas en Mieres sin crear nuevos centros. Esas son, en esencia, las tres alegaciones que el gobierno local de Mieres (IU) ha presentado a la propuesta de Planes Estrat\u00e9gicos de la Universidad de Oviedo dentro del periodo de informaci\u00f3n p\u00fablica abierto por la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,6],"tags":[],"class_list":["post-4355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caudal","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El gobierno de Mieres porf\u00eda por el grado de Deportes: \u201cPonerlo aqu\u00ed cuesta menos\u201d - cm news<\/title>\n<meta name=\"description\" content=\"Tambi\u00e9n reclama en sus alegaciones al plan estrat\u00e9gico del Rectorado mantener Geom\u00e1tica e integrar Minas en la actual oferta de la Polit\u00e9cnica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El gobierno de Mieres porf\u00eda por el grado de Deportes: \u201cPonerlo aqu\u00ed cuesta menos\u201d - cm news\" \/>\n<meta property=\"og:description\" content=\"Tambi\u00e9n reclama en sus alegaciones al plan estrat\u00e9gico del Rectorado mantener Geom\u00e1tica e integrar Minas en la actual oferta de la Polit\u00e9cnica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-18T23:44:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"548\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"El gobierno de Mieres porf\u00eda por el grado de Deportes: \u201cPonerlo aqu\u00ed cuesta menos\u201d\",\"datePublished\":\"2022-02-18T23:44:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\\\/\"},\"wordCount\":406,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215.jpg\",\"articleSection\":[\"Caudal\",\"CM NEWS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\\\/\",\"name\":\"El gobierno de Mieres porf\u00eda por el grado de Deportes: \u201cPonerlo aqu\u00ed cuesta menos\u201d - cm news\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215.jpg\",\"datePublished\":\"2022-02-18T23:44:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"description\":\"Tambi\u00e9n reclama en sus alegaciones al plan estrat\u00e9gico del Rectorado mantener Geom\u00e1tica e integrar Minas en la actual oferta de la Polit\u00e9cnica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215.jpg\",\"width\":1280,\"height\":548},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/18\\\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El gobierno de Mieres porf\u00eda por el grado de Deportes: \u201cPonerlo aqu\u00ed cuesta menos\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El gobierno de Mieres porf\u00eda por el grado de Deportes: \u201cPonerlo aqu\u00ed cuesta menos\u201d - cm news","description":"Tambi\u00e9n reclama en sus alegaciones al plan estrat\u00e9gico del Rectorado mantener Geom\u00e1tica e integrar Minas en la actual oferta de la Polit\u00e9cnica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/","og_locale":"es_ES","og_type":"article","og_title":"El gobierno de Mieres porf\u00eda por el grado de Deportes: \u201cPonerlo aqu\u00ed cuesta menos\u201d - cm news","og_description":"Tambi\u00e9n reclama en sus alegaciones al plan estrat\u00e9gico del Rectorado mantener Geom\u00e1tica e integrar Minas en la actual oferta de la Polit\u00e9cnica.","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/","article_published_time":"2022-02-18T23:44:42+00:00","og_image":[{"width":1280,"height":548,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"El gobierno de Mieres porf\u00eda por el grado de Deportes: \u201cPonerlo aqu\u00ed cuesta menos\u201d","datePublished":"2022-02-18T23:44:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/"},"wordCount":406,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215.jpg","articleSection":["Caudal","CM NEWS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/","name":"El gobierno de Mieres porf\u00eda por el grado de Deportes: \u201cPonerlo aqu\u00ed cuesta menos\u201d - cm news","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215.jpg","datePublished":"2022-02-18T23:44:42+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"description":"Tambi\u00e9n reclama en sus alegaciones al plan estrat\u00e9gico del Rectorado mantener Geom\u00e1tica e integrar Minas en la actual oferta de la Polit\u00e9cnica.","breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/102859ab-492d-4030-aeaf-eede3550d5d1_21-9-aspect-ratio_default_1122215.jpg","width":1280,"height":548},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/18\/el-gobierno-de-mieres-porfia-por-el-grado-de-deportes-ponerlo-aqui-cuesta-menos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"El gobierno de Mieres porf\u00eda por el grado de Deportes: \u201cPonerlo aqu\u00ed cuesta menos\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=4355"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4355\/revisions"}],"predecessor-version":[{"id":4357,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4355\/revisions\/4357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/4356"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=4355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=4355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=4355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}