{"id":4379,"date":"2022-02-25T18:29:26","date_gmt":"2022-02-25T18:29:26","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=4379"},"modified":"2022-02-25T18:30:22","modified_gmt":"2022-02-25T18:30:22","slug":"antroxu-en-las-cuencas","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/","title":{"rendered":"ANTROXU EN LAS CUENCAS"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4380\" src=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/53394319-624x415-1.jpg\" alt=\"\" width=\"624\" height=\"415\" srcset=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/53394319-624x415-1.jpg 624w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/53394319-624x415-1-300x200.jpg 300w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/53394319-624x415-1-272x182.jpg 272w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Langreo<\/strong><\/p>\n<p style=\"text-align: justify;\">Cia\u00f1o celebra el Carnaval el s\u00e1bado 26 de febrero. A las 17.30 tendr\u00e1 lugar el desfile infantil por las calles, que terminar\u00e1 con una chocolatada y magia en el parque Rosario Felgueroso. Organiza la Sociedad de Festejos y Cultura \u201cAmigos de San Esteban\u201d. El momento para los adultos llegar\u00e1 a las 23 horas, con una fiesta en el mismo parque, con el grupo \u201cD\u2019Cano\u201d y varios pinchadiscos. En Sama, la asociaci\u00f3n Hosteler\u00eda de Sama propone un programa del s\u00e1bado al lunes. Restaurantes y sidrer\u00edas ofrecer\u00e1n un men\u00fa especial. El s\u00e1bado, a las 20 horas, habr\u00e1 concurso de disfraces. Ya el lunes ser\u00e1 el desfile por las calles. El infantil empezar\u00e1 a las 17 horas, y el de adultos una hora despu\u00e9s. Habr\u00e1 adem\u00e1s, todos los d\u00edas, talleres de Antroxu, del \u00c1rea de Igualdad, tanto por la ma\u00f1ana (de 10.30 a 13.30 horas) como por la tarde, menos el domingo (de 16 a 19 horas).<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n el lunes 28, en Ria\u00f1o tendr\u00e1 lugar un desfile por las calles a las 17 horas. A continuaci\u00f3n, chocolatada, revoltijo y actuaci\u00f3n de \u201cBailadora T\u00edteres\u201d, con la organizaci\u00f3n de Servicios Sociales y la Asociaci\u00f3n de Vecinos de Ria\u00f1o. Por su parte, La Felguera celebrar\u00e1 su Antroxu el martes 1 de marzo, desde las 17 horas, con la animaci\u00f3n de \u201cGaiteros del carb\u00f3n\u201d. La fiesta ser\u00e1 en el patio del colegio Eulalia \u00c1lvarez, con deportes tradicionales y m\u00fasica. Ejercer\u00e1 de presentador Fernando Valle Roso.<\/p>\n<p style=\"text-align: justify;\"><strong>Laviana<\/strong><\/p>\n<p style=\"text-align: justify;\">Las primeras actividades del Antroxu de las Cuencas comienzan hoy, en Laviana. A las 17 horas, en la plaza del Ayuntamiento se celebrar\u00e1 la gymkana \u201cEl sombrerero loco\u201d, para ni\u00f1os de a partir de 12 a\u00f1os. A las 18 horas, ya en la Casa de Cultura de la Pola, podr\u00e1 verse la obra de \u201cCon Alevos\u00eda Teatro\u201d titulada \u201cElenita\u201d, dirigida a un p\u00fablico familiar, a partir de cuatro a\u00f1os. Hoy viernes, lunes y martes se celebra \u201cConcilia Antroxu\u201d, un campamento urbano par a ni\u00f1os de 4 a 12 a\u00f1os, que tendr\u00e1 lugar en el Cidan de 9 a 14 horas.<\/p>\n<p style=\"text-align: justify;\">El lunes por la ma\u00f1ana habr\u00e1 talleres de Antroxu para ni\u00f1os, en el Cidan. Por la tarde, el acto central de Carnaval, a las 20 horas, con el gran desfile, para el que hay que inscribirse contactando con Aulav antes de las 14 horas de hoy viernes. Hay m\u00e1s de 2.000 euros en premios. El martes, a las 17 horas, en el recinto ferial, tendr\u00e1 lugar la fiesta del Antroxu infantil, y despu\u00e9s, el entierro de la sardina.<\/p>\n<p style=\"text-align: justify;\"><strong>San Mart\u00edn<\/strong><\/p>\n<p style=\"text-align: justify;\">Desde hoy y hasta el lunes 28 se celebra el campamento urbano \u201cAntroxu Camp\u201d, en Blimea, Sotrondio y El Entrego. Ma\u00f1ana s\u00e1bado 26, adem\u00e1s, hay espect\u00e1culo en la calle en Blimea, con el \u201cPasacalles Cicerse\u201d de \u201cVuelta y Media\u201d, a las 16.30 horas. En Sotrondio se podr\u00e1 ver \u201cCazabacterias\u201d, a la misma hora, pero el domingo 27, y en El Entrego el espect\u00e1culo callejero programado se titula \u201cSeres fant\u00e1sticos mitol\u00f3gicos\u201d, a las 17 horas.<\/p>\n<p style=\"text-align: justify;\"><strong>Caso y Sobrescobio<\/strong><\/p>\n<p style=\"text-align: justify;\">En Campo de Caso la fiesta de Carnaval es el s\u00e1bado 26, desde las 16.30 horas, previa inscripci\u00f3n (986608002). Habr\u00e1 hinchables, pintacaras y karaoke. En Rioseco, el Antroxu se celebra el lunes, tambi\u00e9n desde las 16.30 horas, con pintacaras, hinchables y chocolate con churros. Tambi\u00e9n hay que inscribirse (985609005).<\/p>\n<p style=\"text-align: justify;\"><strong>Mieres<\/strong><\/p>\n<p style=\"text-align: justify;\">La truchona \u201cCovidia\u201d del Caudal ser\u00e1 una de las protagonistas del Antroxu, participando en las dos jornadas festivas: el martes 1 de marzo, Antroxu Infantil, y el viernes 4 de marzo, el Gran Antroxu. La programaci\u00f3n infantil arrancar\u00e1 a las 17 horas del martes 1 de marzo con un pasacalles de las charangas \u201cPrincipado\u201d y \u201c\u00c9lite Brass Band\u201d. A las 17.30 horas comenzar\u00e1 el desfile-concurso, abierto a la participaci\u00f3n de grupos, parejas y disfraces individuales. El viernes 4 de marzo ser\u00e1 el Gran Antroxu. A las 12.30 horas, el grupo \u201cEpo producciones\u201d celebrar\u00e1 el velatorio a la truchona \u201cCovidia\u201d en la plaza del Ayuntamiento. A las 19.30 horas habr\u00e1 pasacalles con las charangas \u201cLos Restallones\u201d, \u201cXar\u00e9u Nel \u00d1eru\u201d, \u201cLos Acoplaos\u201d y \u201cLos Tardones\u201d. A continuaci\u00f3n, sobre las 20.30 horas, empezar\u00e1 el desfile del concurso del Carnaval mierense.<\/p>\n<p style=\"text-align: justify;\"><strong>Lena<\/strong><\/p>\n<p style=\"text-align: justify;\">Si Laviana abre los actos del Antroxu, Lena es el municipio encargado de cerrarlos. El Ayuntamiento de Lena celebrar\u00e1 el pr\u00f3ximo 12 de marzo el tradicional Antroxu, que en esta edici\u00f3n prev\u00e9 un incremento de algo m\u00e1s de 2.000 euros (un 49 por ciento m\u00e1s) en la cuant\u00eda de los premios a repartir entre los participantes, con un montante global de 6.480 euros.<\/p>\n<p style=\"text-align: justify;\"><strong>Aller<\/strong><\/p>\n<p style=\"text-align: justify;\">Las celebraciones se centran en la estaci\u00f3n de esqu\u00ed de Fuentes de Invierno, que tiene preparadas actividades desde el s\u00e1bado al martes 1 de marzo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Langreo Cia\u00f1o celebra el Carnaval el s\u00e1bado 26 de febrero. A las 17.30 tendr\u00e1 lugar el desfile infantil por las calles, que terminar\u00e1 con una chocolatada y magia en el parque Rosario Felgueroso. Organiza la Sociedad de Festejos y Cultura \u201cAmigos de San Esteban\u201d. El momento para los adultos llegar\u00e1 a las 23 horas, con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4380,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,6,8],"tags":[],"class_list":["post-4379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caudal","category-noticias","category-nalon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ANTROXU EN LAS CUENCAS - cm news<\/title>\n<meta name=\"description\" content=\"os concejos de la comarca ya celebran el Carnaval, que desde hoy hasta el 12 de marzo centrar\u00e1 la programaci\u00f3n cultural y festiva en los valles mineros.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ANTROXU EN LAS CUENCAS - cm news\" \/>\n<meta property=\"og:description\" content=\"os concejos de la comarca ya celebran el Carnaval, que desde hoy hasta el 12 de marzo centrar\u00e1 la programaci\u00f3n cultural y festiva en los valles mineros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-25T18:29:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-25T18:30:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/53394319-624x415-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"624\" \/>\n\t<meta property=\"og:image:height\" content=\"415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/25\\\/antroxu-en-las-cuencas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/25\\\/antroxu-en-las-cuencas\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"ANTROXU EN LAS CUENCAS\",\"datePublished\":\"2022-02-25T18:29:26+00:00\",\"dateModified\":\"2022-02-25T18:30:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/25\\\/antroxu-en-las-cuencas\\\/\"},\"wordCount\":788,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/25\\\/antroxu-en-las-cuencas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/53394319-624x415-1.jpg\",\"articleSection\":[\"Caudal\",\"CM NEWS\",\"Nal\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/25\\\/antroxu-en-las-cuencas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/25\\\/antroxu-en-las-cuencas\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/25\\\/antroxu-en-las-cuencas\\\/\",\"name\":\"ANTROXU EN LAS CUENCAS - cm news\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/25\\\/antroxu-en-las-cuencas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/25\\\/antroxu-en-las-cuencas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/53394319-624x415-1.jpg\",\"datePublished\":\"2022-02-25T18:29:26+00:00\",\"dateModified\":\"2022-02-25T18:30:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"description\":\"os concejos de la comarca ya celebran el Carnaval, que desde hoy hasta el 12 de marzo centrar\u00e1 la programaci\u00f3n cultural y festiva en los valles mineros.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/25\\\/antroxu-en-las-cuencas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/25\\\/antroxu-en-las-cuencas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/25\\\/antroxu-en-las-cuencas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/53394319-624x415-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/53394319-624x415-1.jpg\",\"width\":624,\"height\":415},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/02\\\/25\\\/antroxu-en-las-cuencas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ANTROXU EN LAS CUENCAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ANTROXU EN LAS CUENCAS - cm news","description":"os concejos de la comarca ya celebran el Carnaval, que desde hoy hasta el 12 de marzo centrar\u00e1 la programaci\u00f3n cultural y festiva en los valles mineros.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/","og_locale":"es_ES","og_type":"article","og_title":"ANTROXU EN LAS CUENCAS - cm news","og_description":"os concejos de la comarca ya celebran el Carnaval, que desde hoy hasta el 12 de marzo centrar\u00e1 la programaci\u00f3n cultural y festiva en los valles mineros.","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/","article_published_time":"2022-02-25T18:29:26+00:00","article_modified_time":"2022-02-25T18:30:22+00:00","og_image":[{"width":624,"height":415,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/53394319-624x415-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"ANTROXU EN LAS CUENCAS","datePublished":"2022-02-25T18:29:26+00:00","dateModified":"2022-02-25T18:30:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/"},"wordCount":788,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/53394319-624x415-1.jpg","articleSection":["Caudal","CM NEWS","Nal\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/","name":"ANTROXU EN LAS CUENCAS - cm news","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/53394319-624x415-1.jpg","datePublished":"2022-02-25T18:29:26+00:00","dateModified":"2022-02-25T18:30:22+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"description":"os concejos de la comarca ya celebran el Carnaval, que desde hoy hasta el 12 de marzo centrar\u00e1 la programaci\u00f3n cultural y festiva en los valles mineros.","breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/53394319-624x415-1.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/02\/53394319-624x415-1.jpg","width":624,"height":415},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/02\/25\/antroxu-en-las-cuencas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"ANTROXU EN LAS CUENCAS"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=4379"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4379\/revisions"}],"predecessor-version":[{"id":4381,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4379\/revisions\/4381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/4380"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=4379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=4379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=4379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}