{"id":4524,"date":"2022-03-30T10:53:31","date_gmt":"2022-03-30T10:53:31","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=4524"},"modified":"2022-03-30T10:53:31","modified_gmt":"2022-03-30T10:53:31","slug":"usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/","title":{"rendered":"Usuarios de la pista finlandesa de Sama, da\u00f1ada en 2019, critican la tardanza en repararla"},"content":{"rendered":"<p style=\"text-align: justify;\">Usuarios de la pista finlandesa de Sama critican la demora acumulada en la ejecuci\u00f3n de las obras de reparaci\u00f3n. El \u00e1rea result\u00f3 da\u00f1ada por el temporal de finales de enero de 2019, hace m\u00e1s de tres a\u00f1os. La actuaci\u00f3n fue adjudicada a principios de diciembre del a\u00f1o pasado. \u201cHace mucho tiempo que no est\u00e1 en condiciones para que se pueda utilizar y necesita que se act\u00fae ya\u201d, indic\u00f3 uno de los vecinos. Los usuarios de la pista finlandesa han reclamado en varias ocasiones a lo largo de los \u00faltimos tres a\u00f1os que se acondicione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4525\" src=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/03\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0-1024x438.jpg\" alt=\"\" width=\"640\" height=\"274\" srcset=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/03\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0-1024x438.jpg 1024w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/03\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0-300x128.jpg 300w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/03\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0-768x329.jpg 768w, https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/03\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0.jpg 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">La obra, que tiene un presupuesto de 17.000 euros y un plazo de ejecuci\u00f3n de dos meses. El Ayuntamiento de Langreo no ha concretado cuando comenzar\u00e1n los trabajos aunque en los \u00faltimos d\u00edas se han realizado trabajos preparatorios en la pista finlandesa, que result\u00f3 afectada por el desbordamiento del r\u00edo Nal\u00f3n. Los trabajos que abordar\u00e1 el Consistorio se centran en el ensanchamiento de las pistas, hasta un ancho medio de 1,50 metros, para permitir el entrenamiento de, al menos, dos usuarios en paralelo. Actualmente tiene entre 1 y 1,20 metros aunque su ancho original llegaba a los 1,50. El espacio quedar\u00e1 reducido para que no se vea afectado por otro posible desbordamiento del r\u00edo.<\/p>\n<p style=\"text-align: justify;\">En el proyecto se incluye la limpieza de los terrenos y otras actuaciones para que no se acumule agua en las \u00e9pocas de lluvias. Tras la riada de enero de 2019, se lleg\u00f3 a barajar un cambio de emplazamiento de la pista finlandesa, traslad\u00e1ndola desde su ubicaci\u00f3n actual en Los Llerones a las proximidades del sanatorio Adaro. Esa opci\u00f3n se estudi\u00f3 en el pasado mandato por parte del anterior ejecutivo municipal, que estaba formado entonces por IU y Somos pero tambi\u00e9n en el actual, con el PSOE en el gobierno local. Sin embargo, al final se decidi\u00f3 que la pista finlandesa se mantuviese en el emplazamiento original. Uno de los motivos esgrimidos es que en el otro terreno alternativo no existe espacio suficiente para una pista con la misma longitud que la actual. En la pista finlandesa de Los Llerones se acometi\u00f3 hace ocho a\u00f1os una mejora. Entonces tambi\u00e9n se vio afectada por las riadas y por obras que se abordaron en el r\u00edo Nal\u00f3n. Tras la inundaci\u00f3n de enero de 2019, en la zona se acumularon \u00e1rboles y maleza que hab\u00eda arrastrado el r\u00edo Nal\u00f3n. Los trabajos para limpiar las riberas fueron ejecutados en marzo de ese mismo a\u00f1o por la Confederaci\u00f3n Hidrogr\u00e1fica del Cant\u00e1brico.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>Fuente: La Nueva Espa\u00f1a<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Usuarios de la pista finlandesa de Sama critican la demora acumulada en la ejecuci\u00f3n de las obras de reparaci\u00f3n. El \u00e1rea result\u00f3 da\u00f1ada por el temporal de finales de enero de 2019, hace m\u00e1s de tres a\u00f1os. La actuaci\u00f3n fue adjudicada a principios de diciembre del a\u00f1o pasado. \u201cHace mucho tiempo que no est\u00e1 en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4525,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,8],"tags":[],"class_list":["post-4524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-nalon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Usuarios de la pista finlandesa de Sama, da\u00f1ada en 2019, critican la tardanza en repararla - cm news<\/title>\n<meta name=\"description\" content=\"La actuaci\u00f3n en la zona deportiva de Los Llerones, que qued\u00f3 anegada, fue adjudicada en diciembre con una inversi\u00f3n de 17.000 euros.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Usuarios de la pista finlandesa de Sama, da\u00f1ada en 2019, critican la tardanza en repararla - cm news\" \/>\n<meta property=\"og:description\" content=\"La actuaci\u00f3n en la zona deportiva de Los Llerones, que qued\u00f3 anegada, fue adjudicada en diciembre con una inversi\u00f3n de 17.000 euros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-30T10:53:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/03\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"548\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/03\\\/30\\\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/03\\\/30\\\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"Usuarios de la pista finlandesa de Sama, da\u00f1ada en 2019, critican la tardanza en repararla\",\"datePublished\":\"2022-03-30T10:53:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/03\\\/30\\\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\\\/\"},\"wordCount\":457,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/03\\\/30\\\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0.jpg\",\"articleSection\":[\"CM NEWS\",\"Nal\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/03\\\/30\\\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/03\\\/30\\\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/03\\\/30\\\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\\\/\",\"name\":\"Usuarios de la pista finlandesa de Sama, da\u00f1ada en 2019, critican la tardanza en repararla - cm news\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/03\\\/30\\\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/03\\\/30\\\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0.jpg\",\"datePublished\":\"2022-03-30T10:53:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"description\":\"La actuaci\u00f3n en la zona deportiva de Los Llerones, que qued\u00f3 anegada, fue adjudicada en diciembre con una inversi\u00f3n de 17.000 euros.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/03\\\/30\\\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/03\\\/30\\\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/03\\\/30\\\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0.jpg\",\"width\":1280,\"height\":548},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2022\\\/03\\\/30\\\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Usuarios de la pista finlandesa de Sama, da\u00f1ada en 2019, critican la tardanza en repararla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Usuarios de la pista finlandesa de Sama, da\u00f1ada en 2019, critican la tardanza en repararla - cm news","description":"La actuaci\u00f3n en la zona deportiva de Los Llerones, que qued\u00f3 anegada, fue adjudicada en diciembre con una inversi\u00f3n de 17.000 euros.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/","og_locale":"es_ES","og_type":"article","og_title":"Usuarios de la pista finlandesa de Sama, da\u00f1ada en 2019, critican la tardanza en repararla - cm news","og_description":"La actuaci\u00f3n en la zona deportiva de Los Llerones, que qued\u00f3 anegada, fue adjudicada en diciembre con una inversi\u00f3n de 17.000 euros.","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/","article_published_time":"2022-03-30T10:53:31+00:00","og_image":[{"width":1280,"height":548,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/03\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"Usuarios de la pista finlandesa de Sama, da\u00f1ada en 2019, critican la tardanza en repararla","datePublished":"2022-03-30T10:53:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/"},"wordCount":457,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/03\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0.jpg","articleSection":["CM NEWS","Nal\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/","name":"Usuarios de la pista finlandesa de Sama, da\u00f1ada en 2019, critican la tardanza en repararla - cm news","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/03\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0.jpg","datePublished":"2022-03-30T10:53:31+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"description":"La actuaci\u00f3n en la zona deportiva de Los Llerones, que qued\u00f3 anegada, fue adjudicada en diciembre con una inversi\u00f3n de 17.000 euros.","breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/03\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2022\/03\/a478d6b1-a43d-4b25-9ad6-d0531f376615_21-9-aspect-ratio_default_0.jpg","width":1280,"height":548},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2022\/03\/30\/usuarios-de-la-pista-finlandesa-de-sama-danada-en-2019-critican-la-tardanza-en-repararla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"Usuarios de la pista finlandesa de Sama, da\u00f1ada en 2019, critican la tardanza en repararla"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=4524"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4524\/revisions"}],"predecessor-version":[{"id":4526,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4524\/revisions\/4526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/4525"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=4524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=4524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=4524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}