{"id":4848,"date":"2023-01-10T15:29:41","date_gmt":"2023-01-10T15:29:41","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=4848"},"modified":"2023-01-10T15:29:41","modified_gmt":"2023-01-10T15:29:41","slug":"pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/","title":{"rendered":"PP MIERES dice a IU que no hay excusas para la CANCELACI\u00d3N de la PISCINA EXTERIOR"},"content":{"rendered":"<p><strong>La subida de la luz no es excusa suficiente para cancelar el proyecto de la piscina exterior en Mieres<\/strong><\/p>\n<ul>\n<li>\u00a0 \u00a0 El equipo de Gobierno demuestra, otra vez, su falta de capacidad de ejecutar proyectos.<\/li>\n<li>\u00a0 \u00a0 El dinero para la piscina fue consignado dentro de los 13 millones de remanentes, por tanto, no le afecta la subida de la luz, el dinero ya esta reservado y en el banco para ello.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>\u00a010 de enero de 2023.-<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p>Seg\u00fan declaraciones de portavoz Municipal del Partido Popular de Mieres: \u201c<em>El dinero para la realizaci\u00f3n del proyecto de la piscina exterior de Vega de Arriba fue consignado con los remanentes municipales y ya est\u00e1 reservado para ello, por tanto, la excusa de la subida de la luz no tiene cabida para justificar el retraso del proyecto. La realidad es la incapacidad del Equipo Municipal de ejecutar proyectos, intentan tapar su incompetencia con excusas peregrinas<\/em>\u201d.<\/p>\n<p>El dinero de los remanentes municipales, la friolera de 13 millones de euros, se los han consumido el Gobierno de Izquierda Unida en apenas dos a\u00f1os, ese es el problema de fondo. Se lo han gastado derrochando y sin sentidos, pero cuando llegaron las vacas flacas, ya no hab\u00eda nada en la hucha, la falta de previsi\u00f3n y gesti\u00f3n es total. Dentro de estos 13 millones hab\u00eda 575.000\u20ac reservados para la piscina, por tanto, ese dinero no se ve afectado por los posibles vaivenes de los cambios del precio de la luz, ya que se trata de un dinero destinado exclusivamente para ese proyecto, no pudiendo destinarse para otro fin o para gasto general, como pretenden hacernos creer el Equipo de Gobierno. Mezclan el presupuesto del a\u00f1o 2023 con el dinero que esquilmaron a los mierenses durante a\u00f1os con unos impuestos alt\u00edsimos.<\/p>\n<p>Durante los \u00faltimos 12 a\u00f1os se ha demostrado una y otra vez la ausencia de capacidad de Izquierda Unida para acometer proyectos: 5 a\u00f1os para hacer el parque de la Mayacina o casi 4 para reformar el puente de Siana, son dos de los muchos existentes. Ahora, que se les echa el tiempo encima para poder llegar al verano de 2023 con piscina, buscan lo que sea para tapar su incompetencia.<\/p>\n<p>\u201c<em>Pedimos al Equipo de Gobierno que no sigan mintiendo a los vecinos de Mieres, tomando por ingenuos a los mierenses y que digan la realidad de su falta de gesti\u00f3n. Si no son capaces de ejecutar los proyectos, que no realicen anuncios electoralistas con fines de enga\u00f1ar a los vecinos con promesas vac\u00edas y carentes de ninguna intenci\u00f3n de realizarse. <\/em><\/p>\n<p><em>Desde el Partido Popular sabemos que la piscina exterior de Vega de Arriba, que venimos reclamando desde hace tantos a\u00f1os, no es una prioridad para Izquierda Unida y sus intereses partidistas. Ya est\u00e1 bien que sigan poniendo excusas vac\u00edas, Mieres necesita una piscina exterior en condiciones ya<\/em>\u201d declar\u00f3 el portavoz municipal Fernando Hern\u00e1ndez.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La subida de la luz no es excusa suficiente para cancelar el proyecto de la piscina exterior en Mieres \u00a0 \u00a0 El equipo de Gobierno demuestra, otra vez, su falta de capacidad de ejecutar proyectos. \u00a0 \u00a0 El dinero para la piscina fue consignado dentro de los 13 millones de remanentes, por tanto, no le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,6],"tags":[224,31,225,125],"class_list":["post-4848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caudal","category-noticias","tag-iu-mieres","tag-mieres","tag-piscina-exterior","tag-pp-mieres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PP MIERES dice a IU que no hay excusas para la CANCELACI\u00d3N de la PISCINA EXTERIOR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PP MIERES dice a IU que no hay excusas para la CANCELACI\u00d3N de la PISCINA EXTERIOR\" \/>\n<meta property=\"og:description\" content=\"La subida de la luz no es excusa suficiente para cancelar el proyecto de la piscina exterior en Mieres \u00a0 \u00a0 El equipo de Gobierno demuestra, otra vez, su falta de capacidad de ejecutar proyectos. \u00a0 \u00a0 El dinero para la piscina fue consignado dentro de los 13 millones de remanentes, por tanto, no le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-10T15:29:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2023\/01\/exterior.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"343\" \/>\n\t<meta property=\"og:image:height\" content=\"147\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/01\\\/10\\\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/01\\\/10\\\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"PP MIERES dice a IU que no hay excusas para la CANCELACI\u00d3N de la PISCINA EXTERIOR\",\"datePublished\":\"2023-01-10T15:29:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/01\\\/10\\\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\\\/\"},\"wordCount\":501,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/01\\\/10\\\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/exterior.jpg\",\"keywords\":[\"iu mieres\",\"mieres\",\"piscina exterior\",\"PP MIERES\"],\"articleSection\":[\"Caudal\",\"CM NEWS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/01\\\/10\\\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/01\\\/10\\\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/01\\\/10\\\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\\\/\",\"name\":\"PP MIERES dice a IU que no hay excusas para la CANCELACI\u00d3N de la PISCINA EXTERIOR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/01\\\/10\\\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/01\\\/10\\\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/exterior.jpg\",\"datePublished\":\"2023-01-10T15:29:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/01\\\/10\\\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/01\\\/10\\\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/01\\\/10\\\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/exterior.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/exterior.jpg\",\"width\":343,\"height\":147},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/01\\\/10\\\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PP MIERES dice a IU que no hay excusas para la CANCELACI\u00d3N de la PISCINA EXTERIOR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PP MIERES dice a IU que no hay excusas para la CANCELACI\u00d3N de la PISCINA EXTERIOR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/","og_locale":"es_ES","og_type":"article","og_title":"PP MIERES dice a IU que no hay excusas para la CANCELACI\u00d3N de la PISCINA EXTERIOR","og_description":"La subida de la luz no es excusa suficiente para cancelar el proyecto de la piscina exterior en Mieres \u00a0 \u00a0 El equipo de Gobierno demuestra, otra vez, su falta de capacidad de ejecutar proyectos. \u00a0 \u00a0 El dinero para la piscina fue consignado dentro de los 13 millones de remanentes, por tanto, no le [&hellip;]","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/","article_published_time":"2023-01-10T15:29:41+00:00","og_image":[{"width":343,"height":147,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2023\/01\/exterior.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"PP MIERES dice a IU que no hay excusas para la CANCELACI\u00d3N de la PISCINA EXTERIOR","datePublished":"2023-01-10T15:29:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/"},"wordCount":501,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2023\/01\/exterior.jpg","keywords":["iu mieres","mieres","piscina exterior","PP MIERES"],"articleSection":["Caudal","CM NEWS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/","name":"PP MIERES dice a IU que no hay excusas para la CANCELACI\u00d3N de la PISCINA EXTERIOR","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2023\/01\/exterior.jpg","datePublished":"2023-01-10T15:29:41+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2023\/01\/exterior.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2023\/01\/exterior.jpg","width":343,"height":147},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/01\/10\/pp-mieres-dice-a-iu-que-no-hay-excusas-para-la-cancelacion-de-la-piscina-exterior\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"PP MIERES dice a IU que no hay excusas para la CANCELACI\u00d3N de la PISCINA EXTERIOR"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=4848"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4848\/revisions"}],"predecessor-version":[{"id":4850,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4848\/revisions\/4850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/4849"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=4848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=4848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=4848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}