{"id":4941,"date":"2023-05-02T18:10:58","date_gmt":"2023-05-02T18:10:58","guid":{"rendered":"https:\/\/www.cuencasmineras.com\/?p=4941"},"modified":"2023-05-02T18:10:58","modified_gmt":"2023-05-02T18:10:58","slug":"pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu","status":"publish","type":"post","link":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/","title":{"rendered":"PP MIERES acusa de PLAGIO en el PROGRAMA ELECTORAL a IU"},"content":{"rendered":"<p><strong>IU de Mieres carece de ideas propias y recurre al plagio para tratar de convencer al electorado, denuncia PP de Mieres ante la copia de su programa electoral<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ul>\n<li>PP de Mieres seguir\u00e1 proponiendo ideas novedosas y necesarias para el progreso de Mieres mientras que IU plagia sus propuestas en un intento desesperado por ganar votos\u00bb<\/li>\n<li>Es inaceptable que IU de Mieres intente presentar como propia una idea que ya ha sido propuesta por el Partido Popular<\/li>\n<\/ul>\n<p><strong><u>Mieres, a 1 de mayo de 2023<\/u><\/strong><\/p>\n<p>El Partido Popular de Mieres denuncia p\u00fablicamente a Izquierda Unida por plagiar sus propuestas electorales en la campa\u00f1a de las pr\u00f3ximas elecciones municipales. Durante los \u00faltimos 4 a\u00f1os, el PP ha venido presentando ideas novedosas y necesarias para el progreso de Mieres, sin embargo, IU ha sido incapaz de desarrollar sus propias propuestas y ha optado por plagiar las del Partido Popular.<\/p>\n<p><strong>La falta de originalidad y la carencia de ideas propias de IU ha quedado patente en varias ocasiones<\/strong>. En primer lugar, IU copi\u00f3 la propuesta de privatizar los servicios de limpieza, la cual hab\u00eda sido presentada por el PP como la \u00fanica forma de lograr la limpieza de las calles de Mieres. En lugar de llamarlo privatizar lo llamaron eufem\u00edsticamente externalizar servicios. En breve acabaremos viendo a IU restructurando la empresa de autobuses o copiando la idea que propusimos de billetes gratuitos.<\/p>\n<p>En segundo lugar, IU ha copiado la idea del Partido Popular de crear un centro de investigaci\u00f3n relacionado con las ciencias de la tierra y la energ\u00eda. El PP ha venido proponiendo durante 4 a\u00f1os la necesidad de crear un cl\u00faster en la zona de Barredo, entre la universidad, la Fundaci\u00f3n de la Energ\u00eda FAEN y la empresa Hunosa. Ahora, IU ha presentado una propuesta similar para un futuro parque tecnol\u00f3gico en Figaredo, y ha optado por llamarlo de otra forma, \u00abcl\u00faster del carb\u00f3n\u00bb.<\/p>\n<p>Sin embargo, la situaci\u00f3n m\u00e1s preocupante ha sido la propuesta de crear una oficina de inversiones, la cual fue presentada por el Partido Popular en las elecciones de 2019 como \u201coficina de captaci\u00f3n de empresas\u201d, idea que consideramos necesaria para Mieres y ya hemos incluido desde hace meses en el programa de 2023. El problema es que esta propuesta es pr\u00e1cticamente id\u00e9ntica a la del Partido Popular de Mieres, pero con un nombre diferente. En aquel momento, el PP propuso esta idea al Alcalde, quien la rechaz\u00f3 rotundamente. Ahora, IU ha presentado la misma propuesta, lo que demuestra su falta de originalidad y su incapacidad para generar ideas propias.<\/p>\n<p><strong>Es inaceptable que IU de Mieres intente presentar como propia una idea que ya ha sido propuesta por el Partido Popular. Es evidente que no tienen ideas propias y que recurren al plagio para tratar de convencer al electorado.<\/strong><\/p>\n<p><strong>El portavoz municipal del PP, Fernando Hern\u00e1ndez, ha declarado que no tienen ning\u00fan problema con que IU copie sus ideas<\/strong>, siempre y cuando se utilicen para el beneficio de Mieres. Lo que no pueden tolerar es que IU haya rechazado estas mismas propuestas en numerosos plenos durante los \u00faltimos 4 a\u00f1os y, ahora, ante la falta de ideas propias, pretendan hacerlas suyas.<\/p>\n<p>El PP seguir\u00e1 proponiendo ideas novedosas y necesarias para el progreso de Mieres y, si IU no tiene ideas propias, est\u00e1n dispuestos a ofrec\u00e9rselas sin ning\u00fan problema. No obstante, el Partido Popular no permitir\u00e1 que IU mienta a los vecinos de Mieres y plagie sus ideas en un intento desesperado por ganar votos. Mieres est\u00e1 muy cerca del punto de no retorno gracias a los 12 a\u00f1os de gobierno nulo de IU, y el Partido Popular no permitir\u00e1 que otros 4 a\u00f1os sean perdidos por la falta de ideas propias de IU. <strong>Est\u00e1 claro que los vecinos de Mieres han de decidor en las elecciones del pr\u00f3ximo d\u00eda 28 entre votar al partido de las ideas originales o al partido del plagio<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>IU de Mieres carece de ideas propias y recurre al plagio para tratar de convencer al electorado, denuncia PP de Mieres ante la copia de su programa electoral \u00a0 PP de Mieres seguir\u00e1 proponiendo ideas novedosas y necesarias para el progreso de Mieres mientras que IU plagia sus propuestas en un intento desesperado por ganar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4881,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[67,31,125],"class_list":["post-4941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-iu","tag-mieres","tag-pp-mieres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PP MIERES acusa de PLAGIO en el PROGRAMA ELECTORAL a IU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PP MIERES acusa de PLAGIO en el PROGRAMA ELECTORAL a IU\" \/>\n<meta property=\"og:description\" content=\"IU de Mieres carece de ideas propias y recurre al plagio para tratar de convencer al electorado, denuncia PP de Mieres ante la copia de su programa electoral \u00a0 PP de Mieres seguir\u00e1 proponiendo ideas novedosas y necesarias para el progreso de Mieres mientras que IU plagia sus propuestas en un intento desesperado por ganar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-02T18:10:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2023\/02\/20230221_132356-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1772\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/05\\\/02\\\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/05\\\/02\\\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"headline\":\"PP MIERES acusa de PLAGIO en el PROGRAMA ELECTORAL a IU\",\"datePublished\":\"2023-05-02T18:10:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/05\\\/02\\\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\\\/\"},\"wordCount\":675,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/05\\\/02\\\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/20230221_132356-scaled.jpg\",\"keywords\":[\"iu\",\"mieres\",\"PP MIERES\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/05\\\/02\\\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/05\\\/02\\\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\\\/\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/05\\\/02\\\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\\\/\",\"name\":\"PP MIERES acusa de PLAGIO en el PROGRAMA ELECTORAL a IU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/05\\\/02\\\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/05\\\/02\\\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/20230221_132356-scaled.jpg\",\"datePublished\":\"2023-05-02T18:10:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/05\\\/02\\\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/05\\\/02\\\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/05\\\/02\\\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/20230221_132356-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuencasmineras.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/20230221_132356-scaled.jpg\",\"width\":1772,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/2023\\\/05\\\/02\\\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PP MIERES acusa de PLAGIO en el PROGRAMA ELECTORAL a IU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuencasmineras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuencasmineras.com\\\/#\\\/schema\\\/person\\\/be0691310e8496ec555f679dd688420c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.cuencasmineras.com\"],\"url\":\"https:\\\/\\\/www.cuencasmineras.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PP MIERES acusa de PLAGIO en el PROGRAMA ELECTORAL a IU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/","og_locale":"es_ES","og_type":"article","og_title":"PP MIERES acusa de PLAGIO en el PROGRAMA ELECTORAL a IU","og_description":"IU de Mieres carece de ideas propias y recurre al plagio para tratar de convencer al electorado, denuncia PP de Mieres ante la copia de su programa electoral \u00a0 PP de Mieres seguir\u00e1 proponiendo ideas novedosas y necesarias para el progreso de Mieres mientras que IU plagia sus propuestas en un intento desesperado por ganar [&hellip;]","og_url":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/","article_published_time":"2023-05-02T18:10:58+00:00","og_image":[{"width":1772,"height":2560,"url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2023\/02\/20230221_132356-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/#article","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/"},"author":{"name":"admin","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"headline":"PP MIERES acusa de PLAGIO en el PROGRAMA ELECTORAL a IU","datePublished":"2023-05-02T18:10:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/"},"wordCount":675,"commentCount":0,"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2023\/02\/20230221_132356-scaled.jpg","keywords":["iu","mieres","PP MIERES"],"articleSection":["Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/","url":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/","name":"PP MIERES acusa de PLAGIO en el PROGRAMA ELECTORAL a IU","isPartOf":{"@id":"https:\/\/www.cuencasmineras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/#primaryimage"},"image":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2023\/02\/20230221_132356-scaled.jpg","datePublished":"2023-05-02T18:10:58+00:00","author":{"@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c"},"breadcrumb":{"@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/#primaryimage","url":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2023\/02\/20230221_132356-scaled.jpg","contentUrl":"https:\/\/www.cuencasmineras.com\/wp-content\/uploads\/2023\/02\/20230221_132356-scaled.jpg","width":1772,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuencasmineras.com\/index.php\/2023\/05\/02\/pp-mieres-acusa-de-plagio-en-el-programa-electoral-a-iu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cuencasmineras.com\/"},{"@type":"ListItem","position":2,"name":"PP MIERES acusa de PLAGIO en el PROGRAMA ELECTORAL a IU"}]},{"@type":"WebSite","@id":"https:\/\/www.cuencasmineras.com\/#website","url":"https:\/\/www.cuencasmineras.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuencasmineras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cuencasmineras.com\/#\/schema\/person\/be0691310e8496ec555f679dd688420c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afd2eed3b2fbbf36dd6707b5bd8a5b50ac648f033e36fbf85aeace2f0f859db?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.cuencasmineras.com"],"url":"https:\/\/www.cuencasmineras.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/comments?post=4941"}],"version-history":[{"count":1,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4941\/revisions"}],"predecessor-version":[{"id":4942,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/posts\/4941\/revisions\/4942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media\/4881"}],"wp:attachment":[{"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/media?parent=4941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/categories?post=4941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuencasmineras.com\/index.php\/wp-json\/wp\/v2\/tags?post=4941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}